{"id":7574,"date":"2023-03-29T17:06:28","date_gmt":"2023-03-29T17:06:28","guid":{"rendered":"http:\/\/192.168.0.235\/elevate\/?page_id=7574"},"modified":"2023-03-29T18:12:17","modified_gmt":"2023-03-29T18:12:17","slug":"appointment","status":"publish","type":"page","link":"https:\/\/reactheme.com\/products\/wordpress\/elevate\/architecture\/appointment\/","title":{"rendered":"Appointment"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"7574\" class=\"elementor elementor-7574\">\n\t\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-cfcc692 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"cfcc692\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-7ebb006\" data-id=\"7ebb006\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-601a8bb elementor-widget elementor-widget-rt-react-image\" data-id=\"601a8bb\" data-element_type=\"widget\" data-widget_type=\"rt-react-image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t                   <div class=\"reveal-item overflow-hidden aos-init\">\n                <div class=\"reveal-animation reveal-end reveal-primary aos aos-init\" data-aos=\"reveal-end\"><\/div>\n                <img decoding=\"async\" class=\"react-multi-image  \" src=\"https:\/\/reactheme.com\/products\/wordpress\/elevate\/architecture\/wp-content\/uploads\/2023\/03\/01-3.webp\" alt=\"image\"\/>\n            <\/div>\n                    \n               \n    \t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-20059dd elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"20059dd\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-4883f36\" data-id=\"4883f36\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3781848 elementor-widget__width-initial elementor-widget elementor-widget-rt-counter\" data-id=\"3781848\" data-element_type=\"widget\" data-widget_type=\"rt-counter.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"counter-top-area no style1\">\r\n\t\t    <div class=\"rts-counter-list\">\r\n\t\t\t\t<div class=\"rts-counter-list-inner\">\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t<div class=\"count-text\">\r\n\t\t\t\t\t\t<div class=\"count-number\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span data-letters=\"500\" class=\"rs-counter\"> 25<\/span>\r\n\t\t\t\t\t\t\t<span class=\"prefix\">Years Experience<\/span>\t\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t\t\r\n\r\n\t\t\t\t\t\t\t\r\n\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\r\n\t\t\t\r\n\r\n\t\t\t<\/div>\r\n\t\t<\/div>\t\t\r\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-7ed30e5\" data-id=\"7ed30e5\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5c56c4e elementor-widget elementor-widget-metform\" data-id=\"5c56c4e\" data-element_type=\"widget\" data-widget_type=\"metform.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div id=\"mf-response-props-id-7601\" data-previous-steps-style=\"\" data-editswitchopen=\"\" data-response_type=\"alert\" data-erroricon=\"fas fa-exclamation-triangle\" data-successicon=\"fas fa-check\" data-messageposition=\"top\" class=\"   mf-scroll-top-no\">\n\t\t<div class=\"formpicker_warper formpicker_warper_editable\" data-metform-formpicker-key=\"7601\" >\n\t\t\t\t\n\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\r\n\t\t<div\r\n\t\t\tid=\"metform-wrap-5c56c4e-7601\"\r\n\t\t\tclass=\"mf-form-wrapper\"\r\n\t\t\tdata-form-id=\"7601\"\r\n\t\t\tdata-action=\"https:\/\/reactheme.com\/products\/wordpress\/elevate\/architecture\/wp-json\/metform\/v1\/entries\/insert\/7601\"\r\n\t\t\tdata-wp-nonce=\"b4973059bc\"\r\n\t\t\tdata-form-nonce=\"d2fbe665e5\"\r\n\t\t\tdata-quiz-summery = \"false\"\r\n\t\t\tdata-save-progress = \"false\"\r\n\t\t\tdata-form-type=\"general-form\"\r\n\t\t\tdata-stop-vertical-effect=\"\"\r\n\t\t\t><\/div>\r\n\r\n\r\n\t\t<!----------------------------- \r\n\t\t\t* controls_data : find the the props passed indie of data attribute\r\n\t\t\t* props.SubmitResponseMarkup : contains the markup of error or success message\r\n\t\t\t* https:\/\/developer.mozilla.org\/en-US\/docs\/Web\/JavaScript\/Reference\/Template_literals\r\n\t\t--------------------------- -->\r\n\r\n\t\t\t\t<script type=\"text\/mf\" class=\"mf-template\">\r\n\t\t\tfunction controls_data (value){\r\n\t\t\t\tlet currentWrapper = \"mf-response-props-id-7601\";\r\n\t\t\t\tlet currentEl = document.getElementById(currentWrapper);\r\n\t\t\t\t\r\n\t\t\t\treturn currentEl ? currentEl.dataset[value] : false\r\n\t\t\t}\r\n\r\n\r\n\t\t\tlet is_edit_mode = '' ? true : false;\r\n\t\t\tlet message_position = controls_data('messageposition') || 'top';\r\n\r\n\t\t\t\r\n\t\t\tlet message_successIcon = controls_data('successicon') || '';\r\n\t\t\tlet message_errorIcon = controls_data('erroricon') || '';\r\n\t\t\tlet message_editSwitch = controls_data('editswitchopen') === 'yes' ? true : false;\r\n\t\t\tlet message_proClass = controls_data('editswitchopen') === 'yes' ? 'mf_pro_activated' : '';\r\n\t\t\t\r\n\t\t\tlet is_dummy_markup = is_edit_mode && message_editSwitch ? true : false;\r\n\r\n\t\t\t\r\n\t\t\treturn html`\r\n\t\t\t\t<form\r\n\t\t\t\t\tclassName=\"metform-form-content\"\r\n\t\t\t\t\tref=${parent.formContainerRef}\r\n\t\t\t\t\tonSubmit=${ validation.handleSubmit( parent.handleFormSubmit ) }\r\n\t\t\t\t\r\n\t\t\t\t\t>\r\n\t\t\t\r\n\t\t\t\r\n\t\t\t\t\t${is_dummy_markup ? message_position === 'top' ?  props.ResponseDummyMarkup(message_successIcon, message_proClass) : '' : ''}\r\n\t\t\t\t\t${is_dummy_markup ? ' ' :  message_position === 'top' ? props.SubmitResponseMarkup`${parent}${state}${message_successIcon}${message_errorIcon}${message_proClass}` : ''}\r\n\r\n\t\t\t\t\t<!--------------------------------------------------------\r\n\t\t\t\t\t*** IMPORTANT \/ DANGEROUS ***\r\n\t\t\t\t\t${html``} must be used as in immediate child of \"metform-form-main-wrapper\"\r\n\t\t\t\t\tclass otherwise multistep form will not run at all\r\n\t\t\t\t\t---------------------------------------------------------->\r\n\r\n\t\t\t\t\t<div className=\"metform-form-main-wrapper\" key=${'hide-form-after-submit'} ref=${parent.formRef}>\r\n\t\t\t\t\t${html`\r\n\t\t\t\t\t\t\t\t<div data-elementor-type=\"wp-post\" key=\"2\" data-elementor-id=\"7601\" className=\"elementor elementor-7601\">\n\t\t\t\t\t\t\t\t\t<section className=\"elementor-section elementor-top-section elementor-element elementor-element-133ebc12 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"133ebc12\" data-element_type=\"section\">\n\t\t\t\t\t\t<div className=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div className=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3bac252b\" data-id=\"3bac252b\" data-element_type=\"column\">\n\t\t\t<div className=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div className=\"elementor-element elementor-element-4fccb3c0 elementor-widget elementor-widget-heading\" data-id=\"4fccb3c0\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div className=\"elementor-widget-container\">\n\t\t\t<style key=\"1\">\/*! elementor - v3.12.1 - 02-04-2023 *\/\n.elementor-heading-title{padding:0;margin:0;line-height:1}.elementor-widget-heading .elementor-heading-title[class*=elementor-size-]>a{color:inherit;font-size:inherit;line-height:inherit}.elementor-widget-heading .elementor-heading-title.elementor-size-small{font-size:15px}.elementor-widget-heading .elementor-heading-title.elementor-size-medium{font-size:19px}.elementor-widget-heading .elementor-heading-title.elementor-size-large{font-size:29px}.elementor-widget-heading .elementor-heading-title.elementor-size-xl{font-size:39px}.elementor-widget-heading .elementor-heading-title.elementor-size-xxl{font-size:59px}<\/style><h3 className=\"elementor-heading-title elementor-size-default\">Make An Appointment\n<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section className=\"elementor-section elementor-inner-section elementor-element elementor-element-3202642d elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"3202642d\" data-element_type=\"section\">\n\t\t\t\t\t\t<div className=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div className=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-379be12b\" data-id=\"379be12b\" data-element_type=\"column\">\n\t\t\t<div className=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div className=\"elementor-element elementor-element-221b58d9 elementor-widget elementor-widget-mf-text\" data-id=\"221b58d9\" data-element_type=\"widget\" data-settings=\"{&quot;mf_input_name&quot;:&quot;mf-first-name&quot;}\" data-widget_type=\"mf-text.default\">\n\t\t\t\t<div className=\"elementor-widget-container\">\n\t\t\t\r\n\t\t<div className=\"mf-input-wrapper\">\r\n\t\t\t\r\n\t\t\t<input\r\n\t\t\t\ttype=\"text\"\r\n\t\t\t\tclassName=\"mf-input mf-conditional-input\"\r\n\t\t\t\tid=\"mf-input-text-221b58d9\"\r\n\t\t\t\tname=\"mf-first-name\"\r\n\t\t\t\tplaceholder=\"${ parent.decodeEntities(`First Name`) } \"\r\n\t\t\t\t\t\t\t\t\tonInput=${parent.handleChange}\r\n\t\t\t\t\tonBlur=${parent.handleChange}\r\n\t\t\t\t\taria-invalid=${validation.errors['mf-first-name'] ? 'true' : 'false'}\r\n\t\t\t\t\tref=${el =>{\r\n\t\t\t\t\t\t\t\t\t\t\t\tparent.activateValidation({\"message\":\"This field is required.\",\"minLength\":1,\"maxLength\":\"\",\"type\":\"none\",\"required\":true,\"expression\":\"null\"}, el)\r\n\t\t\t\t\t}}\r\n\t\t\t\t\t\t\t\t\/>\r\n\r\n\t\t\t\t\t\t\t<${validation.ErrorMessage}\r\n\t\t\t\t\terrors=${validation.errors}\r\n\t\t\t\t\tname=\"mf-first-name\"\r\n\t\t\t\t\tas=${html`<span className=\"mf-error-message\"><\/span>`}\r\n\t\t\t\t\t\/>\r\n\t\t\t\r\n\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div className=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-4f74484\" data-id=\"4f74484\" data-element_type=\"column\">\n\t\t\t<div className=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div className=\"elementor-element elementor-element-5f3fdb09 elementor-widget elementor-widget-mf-text\" data-id=\"5f3fdb09\" data-element_type=\"widget\" data-settings=\"{&quot;mf_input_name&quot;:&quot;mf-last-name&quot;}\" data-widget_type=\"mf-text.default\">\n\t\t\t\t<div className=\"elementor-widget-container\">\n\t\t\t\r\n\t\t<div className=\"mf-input-wrapper\">\r\n\t\t\t\r\n\t\t\t<input\r\n\t\t\t\ttype=\"text\"\r\n\t\t\t\tclassName=\"mf-input mf-conditional-input\"\r\n\t\t\t\tid=\"mf-input-text-5f3fdb09\"\r\n\t\t\t\tname=\"mf-last-name\"\r\n\t\t\t\tplaceholder=\"${ parent.decodeEntities(`Last Name`) } \"\r\n\t\t\t\t\t\t\t\t\tonInput=${parent.handleChange}\r\n\t\t\t\t\tonBlur=${parent.handleChange}\r\n\t\t\t\t\taria-invalid=${validation.errors['mf-last-name'] ? 'true' : 'false'}\r\n\t\t\t\t\tref=${el =>{\r\n\t\t\t\t\t\t\t\t\t\t\t\tparent.activateValidation({\"message\":\"This field is required.\",\"minLength\":1,\"maxLength\":\"\",\"type\":\"none\",\"required\":true,\"expression\":\"null\"}, el)\r\n\t\t\t\t\t}}\r\n\t\t\t\t\t\t\t\t\/>\r\n\r\n\t\t\t\t\t\t\t<${validation.ErrorMessage}\r\n\t\t\t\t\terrors=${validation.errors}\r\n\t\t\t\t\tname=\"mf-last-name\"\r\n\t\t\t\t\tas=${html`<span className=\"mf-error-message\"><\/span>`}\r\n\t\t\t\t\t\/>\r\n\t\t\t\r\n\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section className=\"elementor-section elementor-inner-section elementor-element elementor-element-4d67e19a elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"4d67e19a\" data-element_type=\"section\">\n\t\t\t\t\t\t<div className=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div className=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-6dfaa3dc\" data-id=\"6dfaa3dc\" data-element_type=\"column\">\n\t\t\t<div className=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div className=\"elementor-element elementor-element-41f5625b elementor-widget elementor-widget-mf-telephone\" data-id=\"41f5625b\" data-element_type=\"widget\" data-settings=\"{&quot;mf_input_name&quot;:&quot;mf-tel&quot;}\" data-widget_type=\"mf-telephone.default\">\n\t\t\t\t<div className=\"elementor-widget-container\">\n\t\t\t\n\t\t<div className=\"mf-input-wrapper\">\n\t\t\t\n\t\t\t<input\n\t\t\t\ttype=\"tel\"\n\t\t\t\tclassName=\"mf-input mf-conditional-input\"\n\t\t\t\tid=\"mf-input-telephone-41f5625b\" \n\t\t\t\tname=\"mf-tel\"\n\t\t\t\tplaceholder=\"${ parent.decodeEntities(`Phone Number`) } \"\n\t\t\t\t\t\t\t\t\tonInput=${parent.handleChange}\n\t\t\t\t\taria-invalid=${validation.errors['mf-tel'] ? 'true' : 'false'}\n\t\t\t\t\tref=${el => parent.activateValidation({\"message\":\"This field is required.\",\"minLength\":1,\"maxLength\":\"\",\"type\":\"none\",\"required\":true,\"expression\":\"null\"}, el)}\n\t\t\t\t\t\t\t\t\/>\n\t\t\t\n\t\t\t\t\t\t\t<${validation.ErrorMessage}\n\t\t\t\t\terrors=${validation.errors}\n\t\t\t\t\tname=\"mf-tel\"\n\t\t\t\t\tas=${html`<span className=\"mf-error-message\"><\/span>`}\n\t\t\t\t\t\/>\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div className=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-25a735ec\" data-id=\"25a735ec\" data-element_type=\"column\">\n\t\t\t<div className=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div className=\"elementor-element elementor-element-229a3267 elementor-widget elementor-widget-mf-email\" data-id=\"229a3267\" data-element_type=\"widget\" data-settings=\"{&quot;mf_input_name&quot;:&quot;mf-email&quot;}\" data-widget_type=\"mf-email.default\">\n\t\t\t\t<div className=\"elementor-widget-container\">\n\t\t\t\r\n\t\t<div className=\"mf-input-wrapper\">\r\n\t\t\t\r\n\t\t\t<input \r\n\t\t\t\ttype=\"email\" \r\n\t\t\t\t \r\n\t\t\t\tdefaultValue=\"\" \r\n\t\t\t\tclassName=\"mf-input mf-conditional-input\" \r\n\t\t\t\tid=\"mf-input-email-229a3267\" \r\n\t\t\t\tname=\"mf-email\" \r\n\t\t\t\tplaceholder=\"${ parent.decodeEntities(`Email Address`) } \" \r\n\t\t\t\t \r\n\t\t\t\tonBlur=${parent.handleChange} onFocus=${parent.handleChange} aria-invalid=${validation.errors['mf-email'] ? 'true' : 'false' } \r\n\t\t\t\tref=${el=> parent.activateValidation({\"message\":\"This field is required.\",\"emailMessage\":\"Please enter a valid Email address\",\"minLength\":1,\"maxLength\":\"\",\"type\":\"none\",\"required\":true,\"expression\":\"null\"}, el)}\r\n\t\t\t\t\t\t\t\/>\r\n\r\n\t\t\t\t\t\t<${validation.ErrorMessage} \r\n\t\t\t\terrors=${validation.errors} \r\n\t\t\t\tname=\"mf-email\" \r\n\t\t\t\tas=${html`<span className=\"mf-error-message\"><\/span>`}\r\n\t\t\t\/>\r\n\t\t\t\r\n\t\t\t\t\t<\/div>\r\n\r\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section className=\"elementor-section elementor-inner-section elementor-element elementor-element-7f281331 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"7f281331\" data-element_type=\"section\">\n\t\t\t\t\t\t<div className=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div className=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-5f23e89a\" data-id=\"5f23e89a\" data-element_type=\"column\">\n\t\t\t<div className=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div className=\"elementor-element elementor-element-4adce36c elementor-widget elementor-widget-mf-date\" data-id=\"4adce36c\" data-element_type=\"widget\" data-settings=\"{&quot;mf_input_name&quot;:&quot;mf-checkin-date&quot;}\" data-widget_type=\"mf-date.default\">\n\t\t\t\t<div className=\"elementor-widget-container\">\n\t\t\t\t\t\r\n\t\t<div className=\"mf-input-wrapper\">\r\n\t\t\t\r\n\t\t\t<${props.Flatpickr}\r\n\t\t\t\t\tname=\"mf-checkin-date\"\r\n\t\t\t\t\tclassName=\"mf-input mf-date-input mf-left-parent mf-conditional-input\"\r\n\t\t\t\t\tplaceholder=\"${ parent.decodeEntities(`Select Date`) } \"\r\n\t\t\t\t\toptions=${{\"minDate\":\"yes\",\"maxDate\":\"\",\"dateFormat\":\"d-m-Y\",\"enableTime\":\"\",\"disable\":[],\"mode\":\"single\",\"static\":true,\"disableMobile\":true,\"time_24hr\":false}}\r\n\t\t\t\t\tvalue=${parent.getValue('mf-checkin-date')}\r\n\t\t\t\t\tonInput=${parent.handleDateTime}\r\n\t\t\t\t\taria-invalid=${validation.errors['mf-checkin-date'] ? 'true' : 'false'}\r\n\t\t\t\t\tref=${el => props.DateWidget(\r\n\t\t\t\t\t\t\tel, \r\n\t\t\t\t\t\t\t'', \r\n\t\t\t\t\t\t\t{\"message\":\"This field is required.\",\"required\":true},  \r\n\t\t\t\t\t\t\tregister, \r\n\t\t\t\t\t\t\tparent \r\n\t\t\t\t\t\t)}\r\n\t\t\t\t\t\/>\r\n\r\n\t\t\t\t\t\t\t<${validation.ErrorMessage}\r\n\t\t\t\t\terrors=${validation.errors}\r\n\t\t\t\t\tname=\"mf-checkin-date\"\r\n\t\t\t\t\tas=${html`<span className=\"mf-error-message\"><\/span>`}\r\n\t\t\t\t\t\/>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\r\n\t\t\r\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div className=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-247bec92\" data-id=\"247bec92\" data-element_type=\"column\">\n\t\t\t<div className=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div className=\"elementor-element elementor-element-a8f4293 elementor-widget elementor-widget-mf-time\" data-id=\"a8f4293\" data-element_type=\"widget\" data-settings=\"{&quot;mf_input_name&quot;:&quot;mf-time&quot;}\" data-widget_type=\"mf-time.default\">\n\t\t\t\t<div className=\"elementor-widget-container\">\n\t\t\t\t\t\r\n\t\t\r\n\t\t<div className=\"mf-input-wrapper\">\r\n\t\t\t\t\t\t\r\n\t\t\t<${props.Flatpickr}\r\n\t\t\t\t\tname=\"mf-time\"\r\n\t\t\t\t\tclassName=\"mf-input mf-date-input mf-time-input mf-left-parent \"\r\n\t\t\t\t\tplaceholder=\"${ parent.decodeEntities(`Time`) } \"\r\n\t\t\t\t\toptions=${{\"enableTime\":true,\"dateFormat\":\"h:i K\",\"noCalendar\":true,\"time_24hr\":false,\"static\":true}}\r\n\t\t\t\t\tvalue=${parent.getValue('mf-time')}\r\n\t\t\t\t\tonInput=${parent.handleDateTime}\r\n\t\t\t\t\taria-invalid=${validation.errors['mf-time'] ? 'true' : 'false'}\r\n\t\t\t\t\tref=${\r\n\t\t\t\t\t\tel => {\r\n\t\t\t\t\t\t\tif( el && el.node.nextSibling ) {\r\n\t\t\t\t\t\t\t\tif( el.props.value.trim().length ) {\r\n\t\t\t\t\t\t\t\t\tel.node.nextSibling.classList.add('value-found');\r\n\t\t\t\t\t\t\t\t}else {\r\n\t\t\t\t\t\t\t\t\tel.node.nextSibling.classList.remove('value-found');\r\n\t\t\t\t\t\t\t\t}\r\n\t\t\t\t\t\t\t}\r\n\t\t\t\t\t\t\tregister({ name: \"mf-time\" }, parent.activateValidation({\"message\":\"This field is required.\",\"required\":false}))\r\n\t\t\t\t\t\t}\r\n\t\t\t\t\t}\r\n\t\t\t\t\t\/>\r\n\r\n\t\t\t\t\t\t\t<${validation.ErrorMessage}\r\n\t\t\t\t\terrors=${validation.errors}\r\n\t\t\t\t\tname=\"mf-time\"\r\n\t\t\t\t\tas=${html`<span className=\"mf-error-message\"><\/span>`}\r\n\t\t\t\t\t\/>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\r\n\t\t\r\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section className=\"elementor-section elementor-inner-section elementor-element elementor-element-2ab361ed elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"2ab361ed\" data-element_type=\"section\">\n\t\t\t\t\t\t<div className=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div className=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-402f73f7\" data-id=\"402f73f7\" data-element_type=\"column\">\n\t\t\t<div className=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div className=\"elementor-element elementor-element-630e57f elementor-widget elementor-widget-mf-select\" data-id=\"630e57f\" data-element_type=\"widget\" data-settings=\"{&quot;mf_input_name&quot;:&quot;mf-select&quot;,&quot;mf_input_list&quot;:[{&quot;mf_input_option_text&quot;:&quot;About Construction &quot;,&quot;mf_input_option_value&quot;:&quot;construction&quot;,&quot;_id&quot;:&quot;8beaff0&quot;,&quot;mf_input_option_status&quot;:&quot;&quot;,&quot;mf_input_option_selected&quot;:&quot;&quot;},{&quot;mf_input_option_text&quot;:&quot;About Renovation&quot;,&quot;mf_input_option_value&quot;:&quot;renovation&quot;,&quot;_id&quot;:&quot;f00e063&quot;,&quot;mf_input_option_status&quot;:&quot;&quot;,&quot;mf_input_option_selected&quot;:&quot;&quot;},{&quot;mf_input_option_text&quot;:&quot;About Architecture&quot;,&quot;mf_input_option_value&quot;:&quot;architecture&quot;,&quot;_id&quot;:&quot;7f3c300&quot;,&quot;mf_input_option_status&quot;:&quot;&quot;,&quot;mf_input_option_selected&quot;:&quot;&quot;}]}\" data-widget_type=\"mf-select.default\">\n\t\t\t\t<div className=\"elementor-widget-container\">\n\t\t\t\n\t\t\n\t\t<div className=\"mf-input-wrapper\">\n\t\t\t\n            <${props.Select}\n                className=${\"mf-input mf-input-select  \" + ( validation.errors['mf-select'] ? 'mf-invalid' : '' )}\n                classNamePrefix=\"mf_select\"\n                name=\"mf-select\"\n                placeholder=\"${ parent.decodeEntities(`Select Your Option`) } \"\n                isSearchable=${false}\n                options=${[{\"label\":\"About Construction \",\"value\":\"construction\",\"isDisabled\":false},{\"label\":\"About Renovation\",\"value\":\"renovation\",\"isDisabled\":false},{\"label\":\"About Architecture\",\"value\":\"architecture\",\"isDisabled\":false}]}\n                value=${parent.getValue(\"mf-select\") ? [{\"label\":\"About Construction \",\"value\":\"construction\",\"isDisabled\":false},{\"label\":\"About Renovation\",\"value\":\"renovation\",\"isDisabled\":false},{\"label\":\"About Architecture\",\"value\":\"architecture\",\"isDisabled\":false}].filter(item => item.value === parent.getValue(\"mf-select\"))[0] : []}\n                onChange=${(e)=> parent.handleSelect(e, \"mf-select\")}\n                ref=${() => {\n\t\t\t\t                    register({ name: \"mf-select\" }, parent.activateValidation({\"message\":\"This field is required.\",\"minLength\":1,\"maxLength\":\"\",\"type\":\"none\",\"required\":false}));\n                    if ( parent.getValue(\"mf-select\") === '' && false ) {\n\t\t\t\t    parent.setValue( 'mf-select', '', true );\n                        parent.handleChange({\n                            target: {\n                                name: 'mf-select',\n                                value: ''\n                            }\n                        });\n                    }\n                }}\n                \/>\n\n            \t\t\t\t<${validation.ErrorMessage}\n\t\t\t\t\terrors=${validation.errors}\n\t\t\t\t\tname=\"mf-select\"\n\t\t\t\t\tas=${html`<span className=\"mf-error-message\"><\/span>`}\n\t\t\t\t\t\/>\n\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section className=\"elementor-section elementor-inner-section elementor-element elementor-element-1c0ef6d1 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"1c0ef6d1\" data-element_type=\"section\">\n\t\t\t\t\t\t<div className=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div className=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-657ef9e2\" data-id=\"657ef9e2\" data-element_type=\"column\">\n\t\t\t<div className=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div className=\"elementor-element elementor-element-792c99a3 elementor-widget__width-auto mf-btn--center elementor-widget elementor-widget-mf-button\" data-id=\"792c99a3\" data-element_type=\"widget\" data-widget_type=\"mf-button.default\">\n\t\t\t\t<div className=\"elementor-widget-container\">\n\t\t\t\t\t<div className=\"mf-btn-wraper mf-conditional-input\" data-mf-form-conditional-logic-requirement=\"\">\r\n\t\t\t\t\t\t\t<button type=\"submit\" className=\"metform-btn metform-submit-btn \" id=\"\">\r\n\t\t\t\t\t<span>${ parent.decodeEntities(`Submit Message`) } <\/span>\r\n\t\t\t\t<\/button>\r\n\t\t\t        <\/div>\r\n        \t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t`}\r\n\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t${is_dummy_markup ? message_position === 'bottom' ? props.ResponseDummyMarkup(message_successIcon, message_proClass) : '' : ''}\r\n\t\t\t\t\t${is_dummy_markup ? ' ' : message_position === 'bottom' ? props.SubmitResponseMarkup`${parent}${state}${message_successIcon}${message_errorIcon}${message_proClass}` : ''}\r\n\t\t\t\t\r\n\t\t\t\t<\/form>\r\n\t\t\t`\r\n\t\t<\/script>\r\n\r\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t<\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d00e1c0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d00e1c0\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ad5369d\" data-id=\"ad5369d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-676ee23 elementor-widget__width-inherit elementor-widget elementor-widget-react-heading\" data-id=\"676ee23\" data-element_type=\"widget\" data-widget_type=\"react-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t  \r\n        <div class=\"react-heading default center title-border-no\">\r\n        \t<div class=\"title-inner no\">        \t\t      \t\t\r\n\t            <span class=\"sub-text\" data-aos-delay=\"200\" data-aos=\"fade-up\" data-aos-duration=\"800\" data-aos-once=\"true\">Our latest Blog<\/span><h2 class=\"title\" data-aos-delay=\"300\" data-aos=\"fade-up\" data-aos-duration=\"800\" data-aos-once=\"true\">Blog &amp; Insights<\/h2>\t        <\/div>\r\n\t\t\t\t        \r\n\t            \r\n        <\/div>\r\n        \t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a249c4d elementor-widget elementor-widget-rt-blog-slider\" data-id=\"a249c4d\" data-element_type=\"widget\" data-widget_type=\"rt-blog-slider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t   \r\n                <div class=\"rsaddon-unique-slider gray_no rs-addon-slider rt-blog-slider rt-blog rt-blog-style2 slider-style-2 \">\r\n            <div id=\"rsaddon-slick-slider-21732\" class=\"rt_widget_sliders swiper rtaddon-slider-21732\">\r\n                <div class=\"swiper-wrapper\">\r\n                    \t<div class=\"align-items-center no-gutter blog-item reactheme-blog-grid1 col-md-12 swiper-slide\">\r\n\t\t<div class=\"rts-blog-h-2-wrapper\">\r\n\t\t\t<div class=\"col-top\">\r\n\t\t\t\t<div class=\"image-part\">\r\n\t\t\t\t\t<a href=\"https:\/\/reactheme.com\/products\/wordpress\/elevate\/architecture\/one-of-the-world-largest-passive-house-buildings-construction\/\">\r\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"648\" height=\"500\" src=\"https:\/\/reactheme.com\/products\/wordpress\/elevate\/architecture\/wp-content\/uploads\/2023\/04\/blog-1-648x500.webp\" class=\"attachment-elevate-portfolio-slider size-elevate-portfolio-slider wp-post-image\" alt=\"\" \/>\t\t\t\t\t<\/a> \r\n\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t<div class=\"blog-badge\"> \r\n\t\t\t\t\t\t\t<div class=\"date-2\">\r\n\t\t\t\t\t\t\t\t<span class=\"date\">03<\/span>\r\n\t\t\t\t\t\t\t\t<span class=\"month\">Apr<\/span>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<div class=\"year\">\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t2023\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n\t\t\t<div class=\"col-bottom\">\r\n\t\t\t\t<div class=\"blog-content\">        \r\n\t\t\t\t\t\t\t\t\t<ul class=\"blog-meta\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<li class=\"cat_list\">\r\n\t\t\t\t\t\t\t\t<ul class=\"post-categories\">\n\t<li><a href=\"https:\/\/reactheme.com\/products\/wordpress\/elevate\/architecture\/category\/construction\/\" rel=\"category tag\">Construction<\/a><\/li><\/ul>\t\t\t\t\t\t<\/li>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\r\n\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t<h3 class=\"title dd\"><a href=\"https:\/\/reactheme.com\/products\/wordpress\/elevate\/architecture\/one-of-the-world-largest-passive-house-buildings-construction\/\">One of the World Largest Passive House Buildings Construction<\/a><\/h3>\r\n\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t<div class=\"blog-btn react-button\">\r\n\t\t\t\t\t\t\t<a class=\"rts-read-more btn-primary\" href=\"https:\/\/reactheme.com\/products\/wordpress\/elevate\/architecture\/one-of-the-world-largest-passive-house-buildings-construction\/\">\r\n\t\t\t\t\t\t\tRead More <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"14\" height=\"13\" viewBox=\"0 0 14 13\" fill=\"none\"><path d=\"M11.0039 3.414L2.39691 12.021L0.98291 10.607L9.58891 2H2.00391V-3.8147e-06H13.0039V11H11.0039V3.414Z\" fill=\"white\"><\/path><\/svg><\/a>\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t<\/div>\t\t\t\t\r\n                \t\t\t\t\t\r\n\t\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n\t\t<\/div>\r\n        \r\n    <\/div>\r\n\t\t<div class=\"align-items-center no-gutter blog-item reactheme-blog-grid1 col-md-12 swiper-slide\">\r\n\t\t<div class=\"rts-blog-h-2-wrapper\">\r\n\t\t\t<div class=\"col-top\">\r\n\t\t\t\t<div class=\"image-part\">\r\n\t\t\t\t\t<a href=\"https:\/\/reactheme.com\/products\/wordpress\/elevate\/architecture\/how-to-secure-funding-for-your-new-home-at-london\/\">\r\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"648\" height=\"500\" src=\"https:\/\/reactheme.com\/products\/wordpress\/elevate\/architecture\/wp-content\/uploads\/2023\/04\/blog-2-648x500.webp\" class=\"attachment-elevate-portfolio-slider size-elevate-portfolio-slider wp-post-image\" alt=\"\" \/>\t\t\t\t\t<\/a> \r\n\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t<div class=\"blog-badge\"> \r\n\t\t\t\t\t\t\t<div class=\"date-2\">\r\n\t\t\t\t\t\t\t\t<span class=\"date\">03<\/span>\r\n\t\t\t\t\t\t\t\t<span class=\"month\">Apr<\/span>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<div class=\"year\">\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t2023\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n\t\t\t<div class=\"col-bottom\">\r\n\t\t\t\t<div class=\"blog-content\">        \r\n\t\t\t\t\t\t\t\t\t<ul class=\"blog-meta\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<li class=\"cat_list\">\r\n\t\t\t\t\t\t\t\t<ul class=\"post-categories\">\n\t<li><a href=\"https:\/\/reactheme.com\/products\/wordpress\/elevate\/architecture\/category\/construction\/\" rel=\"category tag\">Construction<\/a><\/li><\/ul>\t\t\t\t\t\t<\/li>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\r\n\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t<h3 class=\"title dd\"><a href=\"https:\/\/reactheme.com\/products\/wordpress\/elevate\/architecture\/how-to-secure-funding-for-your-new-home-at-london\/\">How to Secure Funding for Your New Home at London<\/a><\/h3>\r\n\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t<div class=\"blog-btn react-button\">\r\n\t\t\t\t\t\t\t<a class=\"rts-read-more btn-primary\" href=\"https:\/\/reactheme.com\/products\/wordpress\/elevate\/architecture\/how-to-secure-funding-for-your-new-home-at-london\/\">\r\n\t\t\t\t\t\t\tRead More <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"14\" height=\"13\" viewBox=\"0 0 14 13\" fill=\"none\"><path d=\"M11.0039 3.414L2.39691 12.021L0.98291 10.607L9.58891 2H2.00391V-3.8147e-06H13.0039V11H11.0039V3.414Z\" fill=\"white\"><\/path><\/svg><\/a>\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t<\/div>\t\t\t\t\r\n                \t\t\t\t\t\r\n\t\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n\t\t<\/div>\r\n        \r\n    <\/div>\r\n\t\t<div class=\"align-items-center no-gutter blog-item reactheme-blog-grid1 col-md-12 swiper-slide\">\r\n\t\t<div class=\"rts-blog-h-2-wrapper\">\r\n\t\t\t<div class=\"col-top\">\r\n\t\t\t\t<div class=\"image-part\">\r\n\t\t\t\t\t<a href=\"https:\/\/reactheme.com\/products\/wordpress\/elevate\/architecture\/one-of-the-world-largest-passive-house-buildings-solution\/\">\r\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"648\" height=\"500\" src=\"https:\/\/reactheme.com\/products\/wordpress\/elevate\/architecture\/wp-content\/uploads\/2023\/03\/full-shot-roofers-working-together-with-helmets-648x500.webp\" class=\"attachment-elevate-portfolio-slider size-elevate-portfolio-slider wp-post-image\" alt=\"\" \/>\t\t\t\t\t<\/a> \r\n\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t<div class=\"blog-badge\"> \r\n\t\t\t\t\t\t\t<div class=\"date-2\">\r\n\t\t\t\t\t\t\t\t<span class=\"date\">16<\/span>\r\n\t\t\t\t\t\t\t\t<span class=\"month\">Mar<\/span>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<div class=\"year\">\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t2023\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n\t\t\t<div class=\"col-bottom\">\r\n\t\t\t\t<div class=\"blog-content\">        \r\n\t\t\t\t\t\t\t\t\t<ul class=\"blog-meta\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<li class=\"cat_list\">\r\n\t\t\t\t\t\t\t\t<ul class=\"post-categories\">\n\t<li><a href=\"https:\/\/reactheme.com\/products\/wordpress\/elevate\/architecture\/category\/construction\/\" rel=\"category tag\">Construction<\/a><\/li><\/ul>\t\t\t\t\t\t<\/li>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\r\n\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t<h3 class=\"title dd\"><a href=\"https:\/\/reactheme.com\/products\/wordpress\/elevate\/architecture\/one-of-the-world-largest-passive-house-buildings-solution\/\">One of the World Largest Passive House Buildings Solution<\/a><\/h3>\r\n\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t<div class=\"blog-btn react-button\">\r\n\t\t\t\t\t\t\t<a class=\"rts-read-more btn-primary\" href=\"https:\/\/reactheme.com\/products\/wordpress\/elevate\/architecture\/one-of-the-world-largest-passive-house-buildings-solution\/\">\r\n\t\t\t\t\t\t\tRead More <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"14\" height=\"13\" viewBox=\"0 0 14 13\" fill=\"none\"><path d=\"M11.0039 3.414L2.39691 12.021L0.98291 10.607L9.58891 2H2.00391V-3.8147e-06H13.0039V11H11.0039V3.414Z\" fill=\"white\"><\/path><\/svg><\/a>\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t<\/div>\t\t\t\t\r\n                \t\t\t\t\t\r\n\t\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n\t\t<\/div>\r\n        \r\n    <\/div>\r\n\t\t<div class=\"align-items-center no-gutter blog-item reactheme-blog-grid1 col-md-12 swiper-slide\">\r\n\t\t<div class=\"rts-blog-h-2-wrapper\">\r\n\t\t\t<div class=\"col-top\">\r\n\t\t\t\t<div class=\"image-part\">\r\n\t\t\t\t\t<a href=\"https:\/\/reactheme.com\/products\/wordpress\/elevate\/architecture\/building-smart-business-solution-for-you\/\">\r\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"648\" height=\"500\" src=\"https:\/\/reactheme.com\/products\/wordpress\/elevate\/architecture\/wp-content\/uploads\/2023\/04\/blog-1-648x500.webp\" class=\"attachment-elevate-portfolio-slider size-elevate-portfolio-slider wp-post-image\" alt=\"\" \/>\t\t\t\t\t<\/a> \r\n\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t<div class=\"blog-badge\"> \r\n\t\t\t\t\t\t\t<div class=\"date-2\">\r\n\t\t\t\t\t\t\t\t<span class=\"date\">16<\/span>\r\n\t\t\t\t\t\t\t\t<span class=\"month\">Mar<\/span>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<div class=\"year\">\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t2023\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n\t\t\t<div class=\"col-bottom\">\r\n\t\t\t\t<div class=\"blog-content\">        \r\n\t\t\t\t\t\t\t\t\t<ul class=\"blog-meta\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<li class=\"cat_list\">\r\n\t\t\t\t\t\t\t\t<ul class=\"post-categories\">\n\t<li><a href=\"https:\/\/reactheme.com\/products\/wordpress\/elevate\/architecture\/category\/construction\/\" rel=\"category tag\">Construction<\/a><\/li><\/ul>\t\t\t\t\t\t<\/li>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\r\n\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t<h3 class=\"title dd\"><a href=\"https:\/\/reactheme.com\/products\/wordpress\/elevate\/architecture\/building-smart-business-solution-for-you\/\">Building smart business solution for your Business<\/a><\/h3>\r\n\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t<div class=\"blog-btn react-button\">\r\n\t\t\t\t\t\t\t<a class=\"rts-read-more btn-primary\" href=\"https:\/\/reactheme.com\/products\/wordpress\/elevate\/architecture\/building-smart-business-solution-for-you\/\">\r\n\t\t\t\t\t\t\tRead More <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"14\" height=\"13\" viewBox=\"0 0 14 13\" fill=\"none\"><path d=\"M11.0039 3.414L2.39691 12.021L0.98291 10.607L9.58891 2H2.00391V-3.8147e-06H13.0039V11H11.0039V3.414Z\" fill=\"white\"><\/path><\/svg><\/a>\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t<\/div>\t\t\t\t\r\n                \t\t\t\t\t\r\n\t\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n\t\t<\/div>\r\n        \r\n    <\/div>\r\n\t  \r\n                <\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <script type=\"text\/javascript\"> \r\n            jQuery(document).ready(function(){\r\n                    \r\n                var swiper = new Swiper(\".rtaddon-slider-21732\", {\t\t\t\t\r\n                    slidesPerView: 3,\r\n                    speed: 1000,\r\n                  \r\n                    loop: true,\r\n                   autoplay: false,\r\n                   spaceBetween:  30,\r\n                   pagination: {\r\n                       el: \".swiper-pagination\",\r\n                       clickable: true,\r\n                    },\r\n                    centeredSlides: false,\r\n                    navigation: {\r\n                        nextEl: \".testimonial-cat-next\",\r\n                        prevEl: \".testimonial-cat-prev\",\r\n                    },\r\n                    breakpoints: {     \r\n                        0: {\r\n                            slidesPerView: 1,\r\n                           \r\n                        },                   \r\n                        575: { slidesPerView: 1 },767: { slidesPerView: 2 },991: { slidesPerView: 3 },1199: { slidesPerView: 3 },                        1399: {\r\n                            slidesPerView: 3,\r\n                            spaceBetween:  30                        }\r\n                    }\r\n                });\r\n           \r\n        });\r\n        <\/script>\r\n    \t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>25 Years Experience Our latest Blog Blog &amp; Insights 16 Mar 2023 Construction One of the World Largest Passive House Buildings Solution Read More 16 Mar 2023 Construction Building smart business solution for your Business Read More<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-7574","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/reactheme.com\/products\/wordpress\/elevate\/architecture\/wp-json\/wp\/v2\/pages\/7574","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/reactheme.com\/products\/wordpress\/elevate\/architecture\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/reactheme.com\/products\/wordpress\/elevate\/architecture\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/reactheme.com\/products\/wordpress\/elevate\/architecture\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/reactheme.com\/products\/wordpress\/elevate\/architecture\/wp-json\/wp\/v2\/comments?post=7574"}],"version-history":[{"count":0,"href":"https:\/\/reactheme.com\/products\/wordpress\/elevate\/architecture\/wp-json\/wp\/v2\/pages\/7574\/revisions"}],"wp:attachment":[{"href":"https:\/\/reactheme.com\/products\/wordpress\/elevate\/architecture\/wp-json\/wp\/v2\/media?parent=7574"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}