{"id":9734,"date":"2025-05-15T05:41:39","date_gmt":"2025-05-15T05:41:39","guid":{"rendered":"https:\/\/reactheme.com\/products\/wordpress\/invena-2\/?page_id=32"},"modified":"2025-07-30T11:31:55","modified_gmt":"2025-07-30T11:31:55","slug":"services","status":"publish","type":"page","link":"https:\/\/reactheme.com\/products\/wordpress\/invena\/coach\/services\/","title":{"rendered":"Services"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"9734\" class=\"elementor elementor-9734\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7c026eb e-flex e-con-boxed e-con e-parent\" data-id=\"7c026eb\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1d44c97 elementor-widget__width-initial elementor-widget elementor-widget-react-heading\" data-id=\"1d44c97\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"react-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"react-heading \">\r\n\t\t\t\t<span class=\"watermark\">Our Service<\/span><h2 class=\"title  rts-text-anime-style-1\">Services We Provide <span class=\"stroke_text\"><\/span><\/h2>\t\t\r\n\t\t\t<\/div>\t\r\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8cebe7c elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"8cebe7c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tWith a team of experienced professionals and a passion for innovation, we combine cutting-edge strategies\t\t\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-79cc85c e-con-full e-grid e-con e-child\" data-id=\"79cc85c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-08abde5 elementor-widget elementor-widget-rt-service-grid\" data-id=\"08abde5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"rt-service-grid.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"service-grid-1 item \">\r\n   <div class=\"content-area-wrapper\">\r\n               <div class=\"icon\">\r\n            <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"52\" height=\"52\" viewBox=\"0 0 52 52\" fill=\"none\"><g clip-path=\"url(#clip0_588_123)\"><path d=\"M46.8781 44.6726C46.4054 44.6726 46.0903 44.3574 46.0903 43.8847V14.1816C46.0903 13.5513 45.5388 12.9998 44.9085 12.9998H7.01148C6.38118 12.9998 5.82966 13.5513 5.82966 14.1816V43.8059C5.82966 44.2786 5.51451 44.5938 5.04179 44.5938C4.56906 44.5938 4.25391 44.2786 4.25391 43.8059V14.1816C4.25391 12.6059 5.43572 11.4241 7.01148 11.4241H44.9085C46.4842 11.4241 47.666 12.6059 47.666 14.1816V43.8847C47.666 44.3574 47.3509 44.6726 46.8781 44.6726Z\" fill=\"#20282D\"><\/path><path d=\"M46.9569 19.618H5.04179C4.56906 19.618 4.25391 19.3028 4.25391 18.8301C4.25391 18.3574 4.56906 18.0422 5.04179 18.0422H46.9569C47.4297 18.0422 47.7448 18.3574 47.7448 18.8301C47.7448 19.3028 47.4297 19.618 46.9569 19.618Z\" fill=\"#20282D\"><\/path><path d=\"M22.5333 16.3089H9.6121C9.13937 16.3089 8.82422 15.9938 8.82422 15.521C8.82422 15.0483 9.13937 14.7332 9.6121 14.7332H22.5333C23.006 14.7332 23.3212 15.0483 23.3212 15.521C23.3212 15.9938 23.006 16.3089 22.5333 16.3089Z\" fill=\"#20282D\"><\/path><path d=\"M33.8778 16.3089H33.4051C32.9323 16.3089 32.6172 15.9938 32.6172 15.521C32.6172 15.0483 32.9323 14.7332 33.4051 14.7332H33.8778C34.3505 14.7332 34.6657 15.0483 34.6657 15.521C34.6657 15.9938 34.3505 16.3089 33.8778 16.3089Z\" fill=\"#20282D\"><\/path><path d=\"M38.0536 16.3089H37.5808C37.1081 16.3089 36.793 15.9938 36.793 15.521C36.793 15.0483 37.1081 14.7332 37.5808 14.7332H38.0536C38.5263 14.7332 38.8415 15.0483 38.8415 15.521C38.8415 15.9938 38.5263 16.3089 38.0536 16.3089Z\" fill=\"#20282D\"><\/path><path d=\"M42.3876 16.3089H41.9148C41.4421 16.3089 41.127 15.9938 41.127 15.521C41.127 15.0483 41.4421 14.7332 41.9148 14.7332H42.3876C42.8603 14.7332 43.1754 15.0483 43.1754 15.521C43.1754 15.9938 42.8603 16.3089 42.3876 16.3089Z\" fill=\"#20282D\"><\/path><path d=\"M47.1932 51.3696H4.80529C2.59923 51.3696 0.787109 49.5575 0.787109 47.3514V43.8059C0.787109 43.3332 1.10226 43.0181 1.57499 43.0181H21.272C21.7447 43.0181 22.0598 43.3332 22.0598 43.8059C22.0598 44.2787 21.7447 44.5938 21.272 44.5938H2.36287V47.3514C2.36287 48.6908 3.4659 49.7938 4.80529 49.7938H47.1932C48.5326 49.7938 49.6356 48.6908 49.6356 47.3514V44.5938H30.7265C30.2538 44.5938 29.9386 44.2787 29.9386 43.8059C29.9386 43.3332 30.2538 43.0181 30.7265 43.0181H50.4235C50.8962 43.0181 51.2114 43.3332 51.2114 43.8059V47.3514C51.2114 49.5575 49.3992 51.3696 47.1932 51.3696Z\" fill=\"#20282D\"><\/path><path d=\"M29.0729 47.509H22.8487C21.5093 47.509 20.4062 46.4059 20.4062 45.0666V43.8059C20.4062 43.3332 20.7214 43.0181 21.1941 43.0181C21.6669 43.0181 21.982 43.3332 21.982 43.8059V45.0666C21.982 45.6181 22.4547 45.9332 22.8487 45.9332H29.0729C29.6244 45.9332 29.9396 45.4605 29.9396 45.0666V43.8059C29.9396 43.3332 30.2547 43.0181 30.7275 43.0181C31.2002 43.0181 31.5153 43.3332 31.5153 43.8059V45.0666C31.5153 46.4059 30.4123 47.509 29.0729 47.509Z\" fill=\"#20282D\"><\/path><path d=\"M22.2168 25.606H9.76835C9.29562 25.606 8.98047 25.2909 8.98047 24.8182C8.98047 24.3454 9.29562 24.0303 9.76835 24.0303H22.2168C22.6896 24.0303 23.0047 24.3454 23.0047 24.8182C23.0047 25.2909 22.6896 25.606 22.2168 25.606Z\" fill=\"#20282D\"><\/path><path d=\"M22.2168 30.0181H9.76835C9.29562 30.0181 8.98047 29.703 8.98047 29.2303C8.98047 28.7575 9.29562 28.4424 9.76835 28.4424H22.2168C22.6896 28.4424 23.0047 28.7575 23.0047 29.2303C23.0047 29.703 22.6896 30.0181 22.2168 30.0181Z\" fill=\"#20282D\"><\/path><path d=\"M22.2168 34.5091H9.76835C9.29562 34.5091 8.98047 34.194 8.98047 33.7212C8.98047 33.2485 9.29562 32.9333 9.76835 32.9333H22.2168C22.6896 32.9333 23.0047 33.2485 23.0047 33.7212C23.0047 34.194 22.6896 34.5091 22.2168 34.5091Z\" fill=\"#20282D\"><\/path><path d=\"M22.2168 38.9212H9.76835C9.29562 38.9212 8.98047 38.6061 8.98047 38.1333C8.98047 37.6606 9.29562 37.3455 9.76835 37.3455H22.2168C22.6896 37.3455 23.0047 37.6606 23.0047 38.1333C23.0047 38.6061 22.6896 38.9212 22.2168 38.9212Z\" fill=\"#20282D\"><\/path><path d=\"M22.2163 12.9998C21.9011 12.9998 21.586 12.7635 21.5072 12.4483C21.3496 12.0544 21.3496 11.7392 21.3496 11.5029C21.3496 8.115 24.1072 5.35742 27.4163 5.35742C30.7254 5.35742 33.4829 8.115 33.4829 11.5029C33.4829 11.6605 33.4829 11.818 33.4042 11.9756V12.212C33.4042 12.6847 33.089 12.9998 32.6163 12.9998C32.1436 12.9998 31.8284 12.6847 31.8284 12.212C31.8284 12.0544 31.8284 11.8968 31.9072 11.7392C31.9072 11.6605 31.9072 11.5817 31.9072 11.5029C31.9072 8.98166 29.8587 6.93318 27.4163 6.93318C24.8951 6.93318 22.9254 8.90288 22.9254 11.5029V11.9756C23.0829 12.3695 22.8466 12.8423 22.4526 12.9998C22.3739 12.9998 22.2951 12.9998 22.2163 12.9998Z\" fill=\"#20282D\"><\/path><path d=\"M18.8288 12.9999C18.75 12.9999 18.6712 12.9999 18.5924 12.9211C18.1985 12.7635 17.9621 12.3696 18.1197 11.8969C18.1985 11.7393 18.1985 11.5817 18.1985 11.4241C18.1985 10.7938 17.7258 10.2423 16.8591 9.84837C16.5439 9.6908 16.3076 9.29686 16.3864 8.98171C16.7015 7.56352 17.1742 6.38171 17.9621 5.35746C18.1985 5.04231 18.5924 4.96352 18.9076 5.1211C19.6955 5.51504 20.4833 5.51504 20.8773 5.04231C21.5076 4.41201 21.2712 3.62413 21.0348 3.07262C20.8773 2.67868 21.0348 2.28474 21.35 2.12716C22.453 1.49686 23.6348 0.945343 24.8955 0.630191C25.2894 0.551403 25.6045 0.708979 25.8409 1.02413C26.0773 1.57565 26.6288 2.36352 27.4167 2.36352C28.047 2.36352 28.5985 1.8908 28.9924 1.02413C29.15 0.708979 29.4652 0.472615 29.8591 0.551403C31.1197 0.787767 32.3803 1.33928 33.4833 2.12716C33.7985 2.36352 33.8773 2.67868 33.7985 3.07262C33.4833 3.93928 33.5621 4.72716 33.9561 5.1211C34.35 5.51504 35.1379 5.59383 35.9258 5.27868C36.3197 5.1211 36.7136 5.27868 36.8712 5.59383C37.5015 6.69686 38.053 7.87868 38.3682 9.13928C38.447 9.53322 38.2894 9.92716 37.8955 10.0847C37.1076 10.3999 36.5561 11.0302 36.5561 11.6605C36.5561 11.7393 36.6348 11.9756 36.6348 12.1332L35.1379 12.6059C35.0591 12.2908 34.9015 11.9756 34.9015 11.6605C34.9015 10.6363 35.5318 9.61201 36.5561 8.98171C36.3197 8.27262 36.0833 7.64231 35.6894 7.01201C34.5076 7.32716 33.4045 7.01201 32.6955 6.30292C31.9864 5.59383 31.75 4.4908 31.9864 3.23019C31.3561 2.83625 30.7258 2.59989 30.0167 2.36352C29.3864 3.30898 28.3621 3.93928 27.3379 3.93928C26.3136 3.93928 25.3682 3.38777 24.6591 2.28474C23.95 2.5211 23.3197 2.75746 22.6894 3.1514C23.0045 4.33322 22.7682 5.43625 21.9803 6.22413C21.2712 7.01201 20.1682 7.24837 18.9076 6.93322C18.5924 7.48474 18.2773 8.19383 18.1197 8.90292C19.1439 9.53322 19.7742 10.5575 19.7742 11.5817C19.7742 11.9756 19.6955 12.2908 19.5379 12.5272C19.4591 12.7635 19.1439 12.9999 18.8288 12.9999Z\" fill=\"#20282D\"><\/path><path d=\"M34.3504 25.921C33.8777 25.921 33.5625 25.6059 33.5625 25.1332V23.5574C33.5625 23.0847 33.8777 22.7695 34.3504 22.7695C34.8231 22.7695 35.1383 23.0847 35.1383 23.5574V25.1332C35.1383 25.6059 34.8231 25.921 34.3504 25.921Z\" fill=\"#20282D\"><\/path><path d=\"M29.8584 27.2604C29.622 27.2604 29.4644 27.1816 29.3069 27.0241C29.0705 26.7877 28.9129 26.6301 28.6766 26.3938C28.519 26.1574 28.2826 25.9998 28.125 25.7635C27.8099 25.4483 27.8099 24.9756 28.125 24.6604C28.4402 24.3453 28.9129 24.3453 29.2281 24.6604C29.4644 24.8968 29.622 25.0544 29.8584 25.2907C30.0159 25.5271 30.2523 25.6847 30.4099 25.921C30.725 26.2362 30.725 26.7089 30.4099 27.0241C30.2523 27.1816 30.0947 27.2604 29.8584 27.2604Z\" fill=\"#20282D\"><\/path><path d=\"M27.338 30.727C27.2593 30.727 27.1805 30.727 27.1805 30.727C26.8653 30.6482 26.629 30.5695 26.3138 30.5695C25.9986 30.4907 25.6835 30.4119 25.3683 30.3331C24.9744 30.2543 24.6593 29.7816 24.8168 29.3876C24.8956 28.9937 25.3683 28.6785 25.7623 28.8361C26.0774 28.9149 26.3138 28.9937 26.629 28.9937L27.5744 29.2301C27.9683 29.3088 28.2835 29.7816 28.1259 30.1755C28.0471 30.4907 27.6532 30.727 27.338 30.727Z\" fill=\"#20282D\"><\/path><path d=\"M39.157 27.2604C38.9207 27.2604 38.7631 27.1816 38.6055 27.0241C38.2904 26.7089 38.2904 26.2362 38.6055 25.921C38.7631 25.7635 38.9994 25.5271 39.157 25.2907C39.3934 25.0544 39.551 24.818 39.7873 24.6604C40.1025 24.3453 40.5752 24.3453 40.8904 24.6604C41.2055 24.9756 41.2055 25.4483 40.8904 25.7635C40.7328 25.921 40.4964 26.1574 40.3388 26.3938C40.1025 26.6301 39.9449 26.8665 39.7085 27.0241C39.551 27.1816 39.3934 27.2604 39.157 27.2604Z\" fill=\"#20282D\"><\/path><path d=\"M41.678 30.7272C41.3628 30.7272 40.9689 30.4909 40.8901 30.0969C40.8113 29.703 41.0477 29.2303 41.4416 29.1515L42.3871 28.9151C42.7022 28.8363 42.9386 28.8363 43.2537 28.7575C43.6477 28.6787 44.1204 28.9151 44.1992 29.309C44.278 29.703 44.0416 30.1757 43.6477 30.2545C43.3325 30.3333 43.0174 30.4121 42.7022 30.4909C42.3871 30.5696 42.1507 30.5696 41.8355 30.6484C41.8355 30.7272 41.7568 30.7272 41.678 30.7272Z\" fill=\"#20282D\"><\/path><path d=\"M36.084 40.4968H32.7749C32.3022 40.4968 31.987 40.1816 31.987 39.7089V39.315C31.987 38.2119 31.5143 37.1877 30.5688 36.321C29.0719 34.9029 28.4415 32.8544 28.8355 30.9635C29.3082 28.7574 31.0415 27.0241 33.2476 26.5513C34.9809 26.2362 36.7931 26.6301 38.1325 27.7332C39.4719 28.8362 40.1809 30.4119 40.1809 32.1453C40.1809 33.7998 39.5506 35.2968 38.29 36.3998C37.4234 37.1877 36.8719 38.2907 36.8719 39.3938V39.7089C36.8719 40.1816 36.5567 40.4968 36.084 40.4968ZM33.5628 38.921H35.2961C35.4537 37.5029 36.084 36.2422 37.187 35.218C38.1325 34.4301 38.6052 33.4059 38.6052 32.1453C38.6052 30.8847 38.0537 29.7816 37.1082 28.9938C36.1628 28.2059 34.8234 27.8907 33.5628 28.1271C31.987 28.4422 30.7264 29.7029 30.4112 31.2786C30.0961 32.6968 30.5688 34.1938 31.6719 35.218C32.7749 36.2422 33.4052 37.5029 33.5628 38.921Z\" fill=\"#20282D\"><\/path><\/g><defs><clipPath id=\"clip0_588_123\"><rect width=\"52\" height=\"52\" fill=\"white\"><\/rect><\/clipPath><\/defs><\/svg>         <\/div>\r\n                  <h3 class=\"title\">\r\n            Business Solution         <\/h3>\r\n                  <p class=\"des\">we provide smart, scalable business solutions.<\/p>\r\n         \t     \r\n         <a aria-label=\"service button\" href=\"https:\/\/reactheme.com\/products\/wordpress\/invena\/coach\/business-solution\/\" class=\"button\">Read More <i class=\"rt rt-arrow-right-regular\"><\/i><\/a>\r\n            <\/div>\r\n         <div class=\"thumbnail\">\r\n         <img decoding=\"async\" src=\"https:\/\/reactheme.com\/products\/wordpress\/invena\/coach\/wp-content\/uploads\/2025\/05\/07-1.webp\" alt=\"\">\r\n      <\/div>\r\n      <\/div>\r\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6cb0d2c elementor-widget elementor-widget-rt-service-grid\" data-id=\"6cb0d2c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"rt-service-grid.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"service-grid-1 item \">\r\n   <div class=\"content-area-wrapper\">\r\n               <div class=\"icon\">\r\n            <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"51\" height=\"51\" viewBox=\"0 0 51 51\" fill=\"none\"><path d=\"M17.4774 10.1462C15.9218 10.7338 14.8072 12.2259 14.8072 13.9843C14.8072 14.6615 14.9876 15.2917 15.2788 15.856C14.0449 16.3303 13.1621 17.52 13.1621 18.9197C13.1621 20.3198 14.0449 21.5091 15.2788 21.9838C14.9876 22.5481 14.8072 23.1783 14.8072 23.8551C14.8072 25.6139 15.9218 27.106 17.4774 27.6932C17.3541 28.0378 17.2749 28.4041 17.2749 28.7905C17.2749 30.6051 18.7506 32.0807 20.5652 32.0807C20.9749 32.0807 21.3633 31.996 21.7251 31.8594C22.2581 32.9595 23.3759 33.7259 24.678 33.7259C26.4926 33.7259 27.9683 32.2502 27.9683 30.4356V7.40379C27.9683 5.58956 26.4926 4.11353 24.678 4.11353C23.3759 4.11353 22.2581 4.88026 21.7251 5.97996C21.3633 5.8434 20.9749 5.75866 20.5652 5.75866C18.7506 5.75866 17.2749 7.23469 17.2749 9.04892C17.2749 9.4357 17.3541 9.8016 17.4774 10.1462ZM20.5652 7.40379C21.4725 7.40379 22.2103 8.1416 22.2103 9.04892H23.8555C23.8555 8.25848 23.5635 7.54115 23.0972 6.97363C23.2879 6.27637 23.9205 5.75866 24.678 5.75866C25.5853 5.75866 26.3232 6.49647 26.3232 7.40379V30.4356C26.3232 31.3429 25.5853 32.0807 24.678 32.0807C23.9205 32.0807 23.2879 31.5634 23.0972 30.8658C23.5635 30.2982 23.8555 29.5813 23.8555 28.7905H22.2103C22.2103 29.6978 21.4725 30.4356 20.5652 30.4356C19.6579 30.4356 18.9201 29.6978 18.9201 28.7905C18.9201 27.8832 19.6579 27.1453 20.5652 27.1453V25.5002C19.7639 25.5002 19.0385 25.7998 18.4678 26.277C17.3227 26.0637 16.4524 25.0612 16.4524 23.8551C16.4524 22.4947 17.5597 21.3874 18.9201 21.3874C20.2808 21.3874 21.3878 22.4947 21.3878 23.8551H23.0329C23.0329 21.5874 21.1881 19.7423 18.9201 19.7423C17.9907 19.7423 17.1416 20.064 16.4524 20.5865V20.5648C15.5451 20.5648 14.8072 19.827 14.8072 18.9197C14.8072 18.0124 15.5451 17.2746 16.4524 17.2746V17.2533C17.1416 17.7758 17.9907 18.0971 18.9201 18.0971C21.1881 18.0971 23.0329 16.2524 23.0329 13.9843H21.3878C21.3878 15.3451 20.2808 16.452 18.9201 16.452C17.5597 16.452 16.4524 15.3451 16.4524 13.9843C16.4524 12.7786 17.3227 11.7761 18.4678 11.5628C19.0385 12.04 19.7639 12.3392 20.5652 12.3392V10.694C19.6579 10.694 18.9201 9.95623 18.9201 9.04892C18.9201 8.1416 19.6579 7.40379 20.5652 7.40379Z\" fill=\"#20282D\"><\/path><path d=\"M37.0164 5.75866C36.6067 5.75866 36.2187 5.8434 35.8568 5.97996C35.3234 4.88026 34.2057 4.11353 32.9035 4.11353C31.0889 4.11353 29.6133 5.58956 29.6133 7.40379V30.4356C29.6133 32.2502 31.0889 33.7259 32.9035 33.7259C34.2057 33.7259 35.3234 32.9595 35.8568 31.8594C36.2187 31.996 36.6067 32.0807 37.0164 32.0807C38.831 32.0807 40.3066 30.6051 40.3066 28.7905C40.3066 28.4041 40.2279 28.0378 40.1042 27.6932C41.6598 27.106 42.7743 25.6139 42.7743 23.8551C42.7743 23.1783 42.5944 22.5481 42.3032 21.9838C43.537 21.5091 44.4195 20.3198 44.4195 18.9197C44.4195 17.52 43.537 16.3303 42.3032 15.856C42.5944 15.2917 42.7743 14.6615 42.7743 13.9843C42.7743 12.2259 41.6598 10.7338 40.1042 10.1462C40.2279 9.8016 40.3066 9.4357 40.3066 9.04892C40.3066 7.23469 38.831 5.75866 37.0164 5.75866ZM41.1292 13.9843C41.1292 15.3451 40.0223 16.452 38.6615 16.452C37.3011 16.452 36.1938 15.3451 36.1938 13.9843H34.5487C34.5487 16.2524 36.3938 18.0971 38.6615 18.0971C39.5909 18.0971 40.44 17.7758 41.1292 17.2533V17.2746C42.0365 17.2746 42.7743 18.0124 42.7743 18.9197C42.7743 19.827 42.0365 20.5648 41.1292 20.5648V20.5865C40.44 20.064 39.5909 19.7423 38.6615 19.7423C36.3938 19.7423 34.5487 21.5874 34.5487 23.8551H36.1938C36.1938 22.4947 37.3011 21.3874 38.6615 21.3874C40.0223 21.3874 41.1292 22.4947 41.1292 23.8551C41.1292 25.0612 40.2588 26.0637 39.1142 26.277C38.543 25.7998 37.8176 25.5002 37.0164 25.5002V27.1453C37.9237 27.1453 38.6615 27.8832 38.6615 28.7905C38.6615 29.6978 37.9237 30.4356 37.0164 30.4356C36.1091 30.4356 35.3712 29.6978 35.3712 28.7905H33.7261C33.7261 29.5813 34.0181 30.2982 34.4844 30.8658C34.2936 31.5634 33.661 32.0807 32.9035 32.0807C31.9962 32.0807 31.2584 31.3429 31.2584 30.4356V7.40379C31.2584 6.49647 31.9962 5.75866 32.9035 5.75866C33.661 5.75866 34.2936 6.27637 34.4844 6.97363C34.0181 7.54115 33.7261 8.25848 33.7261 9.04892H35.3712C35.3712 8.1416 36.1091 7.40379 37.0164 7.40379C37.9237 7.40379 38.6615 8.1416 38.6615 9.04892C38.6615 9.95623 37.9237 10.694 37.0164 10.694V12.3392C37.8176 12.3392 38.543 12.04 39.1142 11.5628C40.2588 11.7761 41.1292 12.7786 41.1292 13.9843Z\" fill=\"#20282D\"><\/path><path d=\"M41.7444 5.13048C37.9007 1.5177 32.8665 -0.293711 27.5833 0.03885L27.6853 1.68037C32.5127 1.38034 37.1075 3.03109 40.6182 6.32898C44.1306 9.62969 46.0653 14.102 46.0653 18.9197C46.0653 24.7254 43.1715 30.1091 38.324 33.3214C36.652 34.4299 35.3868 36.0112 34.6072 37.8387H22.9415C22.1511 35.998 20.8811 34.4054 19.2062 33.2869C14.2106 29.948 11.34 24.372 11.5268 18.3686L9.88247 18.3176C9.67763 24.8917 12.8221 30.9991 18.2925 34.6541C19.5006 35.4618 20.4654 36.5615 21.1377 37.8387H18.9206V39.4838H21.794C21.9535 40.0168 22.0812 40.563 22.1458 41.129H20.5658V42.7741H22.2109V45.2418C22.2109 45.6968 22.5796 46.0643 23.0335 46.0643H23.856C23.856 48.7863 26.0695 50.9997 28.7914 50.9997C31.5134 50.9997 33.7268 48.7863 33.7268 46.0643H34.5494C35.0036 46.0643 35.372 45.6968 35.372 45.2418V42.7741H37.0171V41.129H35.4298C35.488 40.5638 35.6041 40.016 35.7603 39.4838H38.6622V37.8387H36.4094C37.0721 36.5755 38.0312 35.4895 39.2334 34.6934C44.5411 31.1734 47.7104 25.2773 47.7104 18.9197C47.7104 13.7196 45.5355 8.69306 41.7444 5.13048ZM28.7914 49.3546C26.9768 49.3546 25.5012 47.879 25.5012 46.0643H32.0817C32.0817 47.879 30.6061 49.3546 28.7914 49.3546ZM33.7268 44.4192H23.856V42.7741H33.7268V44.4192ZM33.7855 41.129H23.7902C23.7351 40.5691 23.6464 40.0188 23.5114 39.4838H34.0413C33.9104 40.018 33.8345 40.5707 33.7855 41.129Z\" fill=\"#20282D\"><\/path><path d=\"M9.04913 5.75869C10.8638 5.75869 12.3394 7.23473 12.3394 9.04895C12.3394 9.50401 12.7081 9.87151 13.162 9.87151C13.6162 9.87151 13.9845 9.50401 13.9845 9.04895C13.9845 7.23473 15.4602 5.75869 17.2748 5.75869C17.729 5.75869 18.0973 5.39118 18.0973 4.93612C18.0973 4.48146 17.729 4.11356 17.2748 4.11356C15.4602 4.11356 13.9845 2.63792 13.9845 0.823297C13.9845 0.368638 13.6162 0.000732422 13.162 0.000732422C12.7081 0.000732422 12.3394 0.368638 12.3394 0.823297C12.3394 2.63792 10.8638 4.11356 9.04913 4.11356C8.59527 4.11356 8.22656 4.48146 8.22656 4.93612C8.22656 5.39118 8.59527 5.75869 9.04913 5.75869ZM13.162 3.54845C13.5274 4.09789 14.0002 4.57103 14.5496 4.93612C14.0002 5.30162 13.5274 5.77435 13.162 6.3238C12.7969 5.77435 12.3237 5.30162 11.7743 4.93612C12.3237 4.57103 12.7969 4.09789 13.162 3.54845Z\" fill=\"#20282D\"><\/path><path d=\"M12.3392 13.9845C12.7935 13.9845 13.1618 13.617 13.1618 13.162C13.1618 12.7073 12.7935 12.3394 12.3392 12.3394C10.5246 12.3394 9.04897 10.8638 9.04897 9.04913C9.04897 8.59447 8.68067 8.22656 8.22641 8.22656C7.77255 8.22656 7.40384 8.59447 7.40384 9.04913C7.40384 10.8638 5.9282 12.3394 4.11358 12.3394C3.65972 12.3394 3.29102 12.7073 3.29102 13.162C3.29102 13.617 3.65972 13.9845 4.11358 13.9845C5.9282 13.9845 7.40384 15.4606 7.40384 17.2748C7.40384 17.7298 7.77255 18.0973 8.22641 18.0973C8.68067 18.0973 9.04897 17.7298 9.04897 17.2748C9.04897 15.4606 10.5246 13.9845 12.3392 13.9845ZM8.22641 14.5496C7.86131 14.0002 7.38818 13.5274 6.83873 13.162C7.38818 12.7969 7.86051 12.3237 8.22641 11.7743C8.5919 12.3237 9.06464 12.7961 9.61408 13.162C9.06464 13.5274 8.5919 14.0002 8.22641 14.5496Z\" fill=\"#20282D\"><\/path><\/svg>         <\/div>\r\n                  <h3 class=\"title\">\r\n            Business Solution         <\/h3>\r\n                  <p class=\"des\">Comprehensive marketing solutions designed.<\/p>\r\n         \t     \r\n         <a aria-label=\"service button\" href=\"https:\/\/reactheme.com\/products\/wordpress\/invena\/coach\/strategy-growth\/\" class=\"button\">Read More <i class=\"rt rt-arrow-right-regular\"><\/i><\/a>\r\n            <\/div>\r\n         <div class=\"thumbnail\">\r\n         <img decoding=\"async\" src=\"https:\/\/reactheme.com\/products\/wordpress\/invena\/coach\/wp-content\/uploads\/2025\/05\/08.webp\" alt=\"\">\r\n      <\/div>\r\n      <\/div>\r\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ed81699 elementor-widget elementor-widget-rt-service-grid\" data-id=\"ed81699\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"rt-service-grid.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"service-grid-1 item img_left\">\r\n   <div class=\"content-area-wrapper\">\r\n               <div class=\"icon\">\r\n            <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"45\" height=\"45\" viewBox=\"0 0 45 45\" fill=\"none\"><g clip-path=\"url(#clip0_3_1279)\"><path d=\"M40.0781 24.2789V10.4906C42.4596 10.1475 44.2969 8.0993 44.2969 5.625C44.2969 2.91164 42.0891 0.703125 39.375 0.703125C36.6609 0.703125 34.4531 2.91164 34.4531 5.625H0.703125V33.75H21.8327C22.1984 39.6253 27.0816 44.2969 33.0469 44.2969C39.2498 44.2969 44.2969 39.2498 44.2969 33.0469C44.2969 29.5038 42.6466 26.3426 40.0781 24.2789ZM39.375 2.10938C41.3135 2.10938 42.8906 3.68648 42.8906 5.625C42.8906 7.56352 41.3135 9.14062 39.375 9.14062C37.4365 9.14062 35.8594 7.56352 35.8594 5.625C35.8594 3.68648 37.4365 2.10938 39.375 2.10938ZM2.10938 7.03125H34.6605C34.8286 7.59234 35.0958 8.10914 35.4389 8.56758L31.1386 12.8679C30.863 12.7357 30.5592 12.6562 30.2344 12.6562C29.9095 12.6562 29.6058 12.7357 29.3309 12.8679L27.9141 11.4511C28.0455 11.1755 28.125 10.8717 28.125 10.5469C28.125 9.38391 27.1786 8.4375 26.0156 8.4375C24.8527 8.4375 23.9062 9.38391 23.9062 10.5469C23.9062 10.8717 23.9857 11.1755 24.1179 11.4504L20.5917 14.9766C20.3161 14.8451 20.0123 14.7656 19.6875 14.7656C18.5245 14.7656 17.5781 15.712 17.5781 16.875C17.5781 18.038 18.5245 18.9844 19.6875 18.9844C20.8505 18.9844 21.7969 18.038 21.7969 16.875C21.7969 16.5502 21.7174 16.2464 21.5852 15.9715L25.1114 12.4453C25.387 12.5768 25.6908 12.6562 26.0156 12.6562C26.3405 12.6562 26.6442 12.5768 26.9191 12.4446L28.3359 13.8614C28.2045 14.137 28.125 14.4408 28.125 14.7656C28.125 15.9286 29.0714 16.875 30.2344 16.875C31.3973 16.875 32.3438 15.9286 32.3438 14.7656C32.3438 14.4408 32.2643 14.137 32.1321 13.8621L36.4331 9.5618C37.0765 10.0441 37.8401 10.3711 38.6719 10.4913V23.3198C37.0146 22.3573 35.0972 21.7969 33.0469 21.7969C29.6859 21.7969 26.6723 23.2861 24.6094 25.631V22.5H20.3906V30.9375H22.0022C21.915 31.3966 21.8623 31.867 21.8327 32.3438H2.10938V7.03125ZM30.2344 14.0625C30.6218 14.0625 30.9375 14.3775 30.9375 14.7656C30.9375 15.1538 30.6218 15.4688 30.2344 15.4688C29.847 15.4688 29.5312 15.1538 29.5312 14.7656C29.5312 14.3775 29.847 14.0625 30.2344 14.0625ZM25.3125 10.5469C25.3125 10.1587 25.6282 9.84375 26.0156 9.84375C26.403 9.84375 26.7188 10.1587 26.7188 10.5469C26.7188 10.935 26.403 11.25 26.0156 11.25C25.6282 11.25 25.3125 10.935 25.3125 10.5469ZM20.3906 16.875C20.3906 17.2631 20.0749 17.5781 19.6875 17.5781C19.3001 17.5781 18.9844 17.2631 18.9844 16.875C18.9844 16.4869 19.3001 16.1719 19.6875 16.1719C20.0749 16.1719 20.3906 16.4869 20.3906 16.875ZM33.0469 38.6719C29.9454 38.6719 27.4219 36.1484 27.4219 33.0469C27.4219 29.9454 29.9454 27.4219 33.0469 27.4219C36.1484 27.4219 38.6719 29.9454 38.6719 33.0469C38.6719 36.1484 36.1484 38.6719 33.0469 38.6719ZM23.2031 27.6124C22.8663 28.2199 22.5879 28.8619 22.3671 29.5312H21.7969V23.9062H23.2031V27.6124ZM32.3438 23.239V26.0515C28.7958 26.4059 26.0156 29.4075 26.0156 33.0469C26.0156 34.0755 26.2434 35.0508 26.6421 35.9325L24.203 37.3409C23.5688 36.0415 23.2031 34.5874 23.2031 33.0469C23.2031 27.8564 27.244 23.6018 32.3438 23.239ZM33.0469 42.8906C29.662 42.8906 26.6709 41.1729 24.8991 38.5629L27.348 37.1489C28.6263 38.9194 30.7013 40.0781 33.0469 40.0781C35.3925 40.0781 37.4674 38.9194 38.7457 37.1489L41.1947 38.5629C39.4228 41.1729 36.4317 42.8906 33.0469 42.8906ZM41.8908 37.3409L39.4516 35.9325C39.8503 35.0508 40.0781 34.0755 40.0781 33.0469C40.0781 29.4075 37.298 26.4052 33.75 26.0515V23.239C38.8498 23.6018 42.8906 27.8564 42.8906 33.0469C42.8906 34.5874 42.525 36.0415 41.8908 37.3409Z\" fill=\"#20282D\"><\/path><path d=\"M33.0469 28.8281C30.7202 28.8281 28.8281 30.7202 28.8281 33.0469C28.8281 35.3735 30.7202 37.2656 33.0469 37.2656C35.3735 37.2656 37.2656 35.3735 37.2656 33.0469C37.2656 30.7202 35.3735 28.8281 33.0469 28.8281ZM33.0469 35.8594C31.4958 35.8594 30.2344 34.598 30.2344 33.0469C30.2344 31.4958 31.4958 30.2344 33.0469 30.2344C34.598 30.2344 35.8594 31.4958 35.8594 33.0469C35.8594 34.598 34.598 35.8594 33.0469 35.8594Z\" fill=\"#20282D\"><\/path><path d=\"M3.51562 8.4375H4.92188V9.84375H3.51562V8.4375Z\" fill=\"#20282D\"><\/path><path d=\"M6.32812 8.4375H16.1719V9.84375H6.32812V8.4375Z\" fill=\"#20282D\"><\/path><path d=\"M3.51562 11.25H4.92188V12.6562H3.51562V11.25Z\" fill=\"#20282D\"><\/path><path d=\"M6.32812 11.25H16.1719V12.6562H6.32812V11.25Z\" fill=\"#20282D\"><\/path><path d=\"M3.51562 14.0625H4.92188V15.4688H3.51562V14.0625Z\" fill=\"#20282D\"><\/path><path d=\"M6.32812 14.0625H16.1719V15.4688H6.32812V14.0625Z\" fill=\"#20282D\"><\/path><path d=\"M3.51562 16.875H4.92188V18.2812H3.51562V16.875Z\" fill=\"#20282D\"><\/path><path d=\"M6.32812 16.875H16.1719V18.2812H6.32812V16.875Z\" fill=\"#20282D\"><\/path><path d=\"M3.51562 30.9375H7.73438V23.9062H3.51562V30.9375ZM4.92188 25.3125H6.32812V29.5312H4.92188V25.3125Z\" fill=\"#20282D\"><\/path><path d=\"M9.14062 30.9375H13.3594V25.3125H9.14062V30.9375ZM10.5469 26.7188H11.9531V29.5312H10.5469V26.7188Z\" fill=\"#20282D\"><\/path><path d=\"M14.7656 30.9375H18.9844V19.6875H14.7656V30.9375ZM16.1719 21.0938H17.5781V29.5312H16.1719V21.0938Z\" fill=\"#20282D\"><\/path><\/g><defs><clipPath id=\"clip0_3_1279\"><rect width=\"45\" height=\"45\" fill=\"white\"><\/rect><\/clipPath><\/defs><\/svg>         <\/div>\r\n                  <h3 class=\"title\">\r\n            Finance Solution         <\/h3>\r\n                  <p class=\"des\">Full-service agency marketing solutions that help brands.<\/p>\r\n         \t     \r\n         <a aria-label=\"service button\" href=\"https:\/\/reactheme.com\/products\/wordpress\/invena\/coach\/finance-solution\/\" class=\"button\">Read More <i class=\"rt rt-arrow-right-regular\"><\/i><\/a>\r\n            <\/div>\r\n         <div class=\"thumbnail\">\r\n         <img decoding=\"async\" src=\"https:\/\/reactheme.com\/products\/wordpress\/invena\/coach\/wp-content\/uploads\/2025\/05\/09.webp\" alt=\"\">\r\n      <\/div>\r\n      <\/div>\r\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-29ff70d elementor-widget elementor-widget-rt-service-grid\" data-id=\"29ff70d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"rt-service-grid.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"service-grid-1 item img_left\">\r\n   <div class=\"content-area-wrapper\">\r\n               <div class=\"icon\">\r\n            <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"52\" height=\"52\" viewBox=\"0 0 52 52\" fill=\"none\"><path d=\"M25.1875 5.22539V3.28687C25.1875 2.83816 25.5513 2.47437 26 2.47437C26.4487 2.47437 26.8125 2.83816 26.8125 3.28687V5.22539C26.8125 5.67409 26.4487 6.03789 26 6.03789C25.5513 6.03789 25.1875 5.67419 25.1875 5.22539ZM19.0893 7.29483C19.2398 7.55544 19.5129 7.70118 19.7937 7.70118C19.9315 7.70118 20.0713 7.66604 20.1993 7.5922C20.5878 7.36785 20.721 6.8709 20.4966 6.48233L19.5274 4.8035C19.3031 4.41482 18.8061 4.28197 18.4175 4.50612C18.029 4.73047 17.8958 5.22742 18.1202 5.616L19.0893 7.29483ZM13.1639 11.1669L14.8427 12.1361C14.9707 12.21 15.1104 12.2451 15.2483 12.2451C15.5291 12.2451 15.8022 12.0993 15.9527 11.8387C16.1771 11.4502 16.0439 10.9532 15.6554 10.7289L13.9765 9.75965C13.5879 9.53519 13.091 9.66834 12.8666 10.057C12.6422 10.4456 12.7753 10.9425 13.1639 11.1669ZM31.8008 7.5923C31.9288 7.66624 32.0685 7.70128 32.2064 7.70128C32.4872 7.70128 32.7603 7.55554 32.9108 7.29493L33.88 5.6161C34.1044 5.22742 33.9712 4.73058 33.5827 4.50622C33.194 4.28177 32.697 4.41492 32.4728 4.8036L31.5036 6.48243C31.2791 6.87101 31.4123 7.36795 31.8008 7.5923ZM36.7517 12.2452C36.8895 12.2452 37.0293 12.21 37.1572 12.1362L38.8361 11.167C39.2247 10.9426 39.3578 10.4457 39.1335 10.0571C38.9091 9.66855 38.4122 9.5355 38.0236 9.75975L36.3447 10.729C35.9562 10.9533 35.823 11.4503 36.0474 11.8388C36.1979 12.0994 36.471 12.2452 36.7517 12.2452ZM40.5496 36.01C40.2961 36.9537 39.9515 37.8681 39.52 38.7436H41.935C42.2337 38.7436 42.5084 38.9076 42.6502 39.1705L43.7827 41.2717H45.0114C45.3549 40.2134 46.3498 39.4459 47.5211 39.4459C48.9759 39.4459 50.1594 40.6294 50.1594 42.0842C50.1594 43.5388 48.9759 44.7224 47.5211 44.7224C46.3498 44.7224 45.3549 43.9549 45.0115 42.8967H43.2977C42.9989 42.8967 42.7243 42.7326 42.5825 42.4697L41.45 40.3686H39.3936L40.0848 41.925C40.2212 42.2321 40.1545 42.5916 39.9167 42.8293L36.736 46.0102C36.4983 46.2478 36.1389 46.3146 35.8317 46.1782L33.5181 45.1507C32.3853 45.8044 31.1772 46.3052 29.9164 46.6438L29.0076 49.0048C28.8869 49.3186 28.5855 49.5254 28.2493 49.5254H23.751C23.4148 49.5254 23.1135 49.3185 22.9927 49.0048L22.0836 46.6432C20.8237 46.3047 19.6158 45.8039 18.4831 45.1503L16.1685 46.1782C15.8613 46.3147 15.502 46.2479 15.2642 46.0102L12.0834 42.8294C11.8457 42.5918 11.7789 42.2323 11.9153 41.9251L12.6066 40.3686H10.5501L9.41759 42.4697C9.2758 42.7326 9.00118 42.8967 8.70238 42.8967H6.98862C6.64513 43.9549 5.65023 44.7224 4.47901 44.7224C3.02423 44.7224 1.84072 43.5389 1.84072 42.0842C1.84072 40.6294 3.02423 39.4459 4.47901 39.4459C5.65023 39.4459 6.64523 40.2134 6.98872 41.2717H8.21742L9.34995 39.1705C9.49173 38.9076 9.76635 38.7436 10.0651 38.7436H12.4793C12.048 37.8683 11.7035 36.9538 11.4499 36.0098L9.08883 35.1009C8.7751 34.9803 8.56822 34.6788 8.56822 34.3427V32.9059H5.9605C5.61702 33.9642 4.62211 34.7317 3.45079 34.7317C1.99601 34.7318 0.8125 33.5482 0.8125 32.0935C0.8125 30.6389 1.99601 29.4553 3.45079 29.4553C4.62211 29.4553 5.61702 30.2228 5.9605 31.281H8.56822V29.8444C8.56822 29.5083 8.7752 29.2069 9.08883 29.0862L11.4503 28.1772C11.7038 27.2331 12.0485 26.3184 12.4802 25.4427H10.0651C9.76635 25.4427 9.49173 25.2787 9.34995 25.0158L8.21742 22.9146H6.98872C6.64523 23.9729 5.65033 24.7404 4.47911 24.7404C3.02433 24.7404 1.84082 23.5569 1.84082 22.1021C1.84082 20.6475 3.02433 19.4638 4.47911 19.4638C5.65033 19.4638 6.64523 20.2314 6.98872 21.2896H8.70248C9.00128 21.2896 9.27591 21.4537 9.41769 21.7166L10.5502 23.8177H12.6063L11.9154 22.2622C11.779 21.9551 11.8457 21.5956 12.0834 21.3579L15.2641 18.1769C15.5018 17.9393 15.8613 17.8726 16.1684 18.0089L17.2277 18.4793C17.0635 17.8613 16.9578 17.1349 16.9578 16.2371C16.9578 11.2512 21.0141 7.19489 26.0001 7.19489C30.986 7.19489 35.0423 11.2512 35.0423 16.2371C35.0423 17.1255 34.9405 17.8507 34.7736 18.4788L35.8316 18.009C36.1386 17.8727 36.4981 17.9393 36.7359 18.177L39.9167 21.3578C40.1544 21.5954 40.2212 21.9549 40.0848 22.2621L39.3939 23.8178H41.45L42.5825 21.7167C42.7243 21.4538 42.9989 21.2897 43.2977 21.2897H45.0115C45.355 20.2315 46.3499 19.4639 47.5211 19.4639C48.9759 19.4639 50.1594 20.6475 50.1594 22.1022C50.1594 23.557 48.9759 24.7405 47.5211 24.7405C46.3498 24.7405 45.3549 23.9731 45.0114 22.9147H43.7826L42.6501 25.0159C42.5083 25.2788 42.2337 25.4428 41.9349 25.4428H39.5204C39.952 26.3184 40.2966 27.2332 40.5504 28.1775L42.9114 29.0863C43.225 29.2069 43.432 29.5084 43.432 29.8445V31.2811H46.0396C46.3831 30.2229 47.378 29.4554 48.5492 29.4554C50.004 29.4554 51.1875 30.6389 51.1875 32.0936C51.1875 33.5484 50.004 34.7319 48.5492 34.7319C47.3779 34.7319 46.383 33.9644 46.0395 32.9061H43.4319V34.3429C43.4319 34.679 43.2249 34.9804 42.9113 35.1011L40.5496 36.01ZM47.5359 32.0935C47.5359 32.6522 47.9905 33.1068 48.5492 33.1068C49.1079 33.1068 49.5625 32.6522 49.5625 32.0935C49.5625 31.5349 49.1079 31.0803 48.5492 31.0803C47.9905 31.0803 47.5359 31.5349 47.5359 32.0935ZM46.5077 22.102C46.5077 22.6607 46.9623 23.1153 47.521 23.1153C48.0797 23.1153 48.5343 22.6607 48.5343 22.102C48.5343 21.5433 48.0797 21.0887 47.521 21.0887C46.9622 21.0888 46.5077 21.5433 46.5077 22.102ZM5.4923 22.102C5.4923 21.5433 5.0377 21.0887 4.47901 21.0887C3.92031 21.0887 3.46572 21.5433 3.46572 22.102C3.46572 22.6607 3.92031 23.1153 4.47901 23.1153C5.0377 23.1153 5.4923 22.6607 5.4923 22.102ZM4.46408 32.0935C4.46408 31.5349 4.00948 31.0803 3.45079 31.0803C2.89209 31.0803 2.4375 31.5349 2.4375 32.0935C2.4375 32.6522 2.89209 33.1068 3.45079 33.1068C4.00948 33.1068 4.46408 32.6522 4.46408 32.0935ZM5.4923 42.0842C5.4923 41.5255 5.0377 41.0709 4.47901 41.0709C3.92031 41.0709 3.46572 41.5255 3.46572 42.0842C3.46572 42.6428 3.92031 43.0974 4.47901 43.0974C5.0377 43.0974 5.4923 42.6428 5.4923 42.0842ZM46.5077 42.0842C46.5077 42.6428 46.9623 43.0974 47.521 43.0974C48.0797 43.0974 48.5343 42.6428 48.5343 42.0842C48.5343 41.5255 48.0797 41.0709 47.521 41.0709C46.9622 41.0709 46.5077 41.5255 46.5077 42.0842ZM18.5827 16.2371C18.5827 17.685 18.8935 18.5667 19.3601 19.4455C19.5011 19.7109 19.6546 19.9732 19.8172 20.251C20.5867 21.5661 21.5312 23.1805 21.839 26.4594H23.7663V19.0226H22.6664C21.1639 19.0226 19.9415 17.8001 19.9415 16.2976C19.9415 14.7951 21.1639 13.5727 22.6664 13.5727C24.1689 13.5727 25.3913 14.7951 25.3913 16.2976V17.3976H26.6087V16.2976C26.6087 14.7951 27.8311 13.5727 29.3336 13.5727C30.8361 13.5727 32.0585 14.7951 32.0585 16.2976C32.0585 17.8001 30.8361 19.0226 29.3336 19.0226H28.2337V26.4594H30.1609C30.4686 23.1805 31.4133 21.5662 32.1827 20.2511C32.8724 19.0723 33.4172 18.1413 33.4172 16.2372C33.4172 12.1473 30.0898 8.81999 26 8.81999C21.9101 8.81989 18.5827 12.1472 18.5827 16.2371ZM23.7663 16.2976C23.7663 15.6911 23.2729 15.1977 22.6664 15.1977C22.0599 15.1977 21.5665 15.6911 21.5665 16.2976C21.5665 16.9042 22.0599 17.3976 22.6664 17.3976H23.7663V16.2976ZM26.6087 19.0226H25.3913V26.4594H26.6087V19.0226ZM21.8985 28.0843V28.6092C21.8985 28.8937 22.1388 29.134 22.4233 29.134H29.5766C29.8611 29.134 30.1014 28.8937 30.1014 28.6092V28.0843H21.8985ZM24.6522 33.9587C24.6522 34.2432 24.8925 34.4835 25.1769 34.4835H26.9125C27.197 34.4835 27.4373 34.2432 27.4373 33.9587V33.4338H24.6522V33.9587ZM28.8088 30.759H23.2806V31.2839C23.2806 31.5684 23.521 31.8087 23.8054 31.8087H28.284C28.5685 31.8087 28.8088 31.5684 28.8088 31.2839V30.759ZM20.2491 26.9426C18.9855 28.3452 18.2818 30.1573 18.2818 32.0935C18.2818 36.3494 21.7441 39.8118 26 39.8118C30.2559 39.8118 33.7182 36.3494 33.7182 32.0935C33.7182 30.1573 33.0144 28.3451 31.7508 26.9425C31.7419 27.0589 31.7337 27.1771 31.7265 27.2984V28.6093C31.7265 29.4901 31.1936 30.2479 30.4338 30.5798V31.2841C30.4338 32.1948 29.8636 32.9732 29.0623 33.2859V33.9589C29.0623 35.1444 28.0979 36.1087 26.9125 36.1087H25.1769C23.9915 36.1087 23.0272 35.1443 23.0272 33.9589V33.2859C22.2258 32.9732 21.6557 32.1948 21.6557 31.2841V30.615C20.8489 30.305 20.2736 29.524 20.2736 28.6094V27.2993C20.2663 27.1776 20.2581 27.0592 20.2491 26.9426ZM29.3336 17.3976C29.9401 17.3976 30.4335 16.9042 30.4335 16.2976C30.4335 15.6911 29.9401 15.1977 29.3336 15.1977C28.7271 15.1977 28.2337 15.6911 28.2337 16.2976V17.3976H29.3336ZM39.5734 34.6445L41.8069 33.7848V30.4022L39.5741 29.5428C39.3242 29.4466 39.1376 29.2332 39.0756 28.9726C38.7462 27.5883 38.1999 26.2707 37.452 25.0562C37.3115 24.8281 37.2925 24.5452 37.4012 24.3004L38.373 22.1122L35.9811 19.7204L33.8102 20.6845C33.736 20.8136 33.6609 20.9423 33.5852 21.0716C32.99 22.0886 32.3805 23.1319 32.0162 24.945C34.1367 26.7258 35.3431 29.3031 35.3431 32.0934C35.3431 37.2453 31.1518 41.4367 25.9999 41.4367C20.848 41.4367 16.6567 37.2453 16.6567 32.0934C16.6567 29.3032 17.8631 26.7259 19.9836 24.9451C19.6193 23.1319 19.0098 22.0885 18.4146 21.0715C18.3404 20.9446 18.265 20.8152 18.1901 20.6847L16.0186 19.7203L13.6268 22.1122L14.5989 24.3009C14.7077 24.5457 14.6887 24.8285 14.5481 25.0567C13.8001 26.2713 13.2539 27.5887 12.9248 28.9722C12.8629 29.2328 12.6763 29.4462 12.4263 29.5424L10.193 30.402V33.7847L12.4258 34.6441C12.6758 34.7403 12.8623 34.9535 12.9243 35.2143C13.2538 36.5988 13.8 37.9164 14.5478 39.1306C14.6884 39.3588 14.7074 39.6416 14.5986 39.8864L13.6268 42.0746L16.0187 44.4664L18.2077 43.4942C18.4525 43.3855 18.7352 43.4044 18.9634 43.5449C20.1782 44.2928 21.4955 44.839 22.8788 45.1682C23.1394 45.2303 23.3527 45.4167 23.4489 45.6668L24.3086 47.9002H27.6912L28.5506 45.6675C28.6468 45.4174 28.8602 45.231 29.1208 45.1689C30.5051 44.8395 31.8228 44.2933 33.0371 43.5454C33.2653 43.4049 33.5479 43.3859 33.7929 43.4947L35.9811 44.4664L38.3729 42.0745L37.4007 39.8856C37.2919 39.6408 37.3109 39.358 37.4515 39.1299C38.1994 37.9152 38.7455 36.5978 39.0747 35.2146C39.137 34.9541 39.3235 34.7407 39.5734 34.6445Z\" fill=\"#20282D\"><\/path><\/svg>         <\/div>\r\n                  <h3 class=\"title\">\r\n            Business Marketing         <\/h3>\r\n                  <p class=\"des\">Our business marketing services are designed.<\/p>\r\n         \t     \r\n         <a aria-label=\"service button\" href=\"https:\/\/reactheme.com\/products\/wordpress\/invena\/coach\/market-research\/\" class=\"button\">Read More <i class=\"rt rt-arrow-right-regular\"><\/i><\/a>\r\n            <\/div>\r\n         <div class=\"thumbnail\">\r\n         <img decoding=\"async\" src=\"https:\/\/reactheme.com\/products\/wordpress\/invena\/coach\/wp-content\/uploads\/2025\/05\/10-1.webp\" alt=\"service\">\r\n      <\/div>\r\n      <\/div>\r\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-02fb04f elementor-absolute elementor-hidden-mobile elementor-widget elementor-widget-rt-react-image\" data-id=\"02fb04f\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"rt-react-image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n        <div class=\"react-image animate-yes   \">\n                            <img decoding=\"async\" loading=\"lazy\" class=\"react-multi-image   vertical   \" src=\"https:\/\/reactheme.com\/products\/wordpress\/invena\/coach\/wp-content\/uploads\/2025\/05\/03.webp\" alt=\"\"\/>\n                    <\/div>\n\n               \n    \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-101966e elementor-absolute elementor-hidden-mobile elementor-widget elementor-widget-rt-react-image\" data-id=\"101966e\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"rt-react-image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n        <div class=\"react-image animate-yes   \">\n                            <img decoding=\"async\" loading=\"lazy\" class=\"react-multi-image   vertical   \" src=\"https:\/\/reactheme.com\/products\/wordpress\/invena\/coach\/wp-content\/uploads\/2025\/05\/shape_3.webp\" alt=\"\"\/>\n                    <\/div>\n\n               \n    \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-15abfc0 elementor-absolute elementor-hidden-mobile elementor-widget elementor-widget-rt-react-image\" data-id=\"15abfc0\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"rt-react-image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n        <div class=\"react-image animate-yes   \">\n                            <img decoding=\"async\" loading=\"lazy\" class=\"react-multi-image   vertical   \" src=\"https:\/\/reactheme.com\/products\/wordpress\/invena\/coach\/wp-content\/uploads\/2025\/05\/02.webp\" alt=\"\"\/>\n                    <\/div>\n\n               \n    \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f7d7434 e-flex e-con-boxed e-con e-parent\" data-id=\"f7d7434\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-4e48605 e-con-full e-flex e-con e-child\" data-id=\"4e48605\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ae14b22 elementor-widget elementor-widget-react-heading\" data-id=\"ae14b22\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"react-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"react-heading \">\r\n\t\t\t\t<span class=\"sub-text\">How we works<\/span><h2 class=\"title  rts-text-anime-style-1\">Easy 3 Steps To Work <span class=\"stroke_text\"><\/span><\/h2>\t\t\r\n\t\t\t<\/div>\t\r\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8291e3b elementor-invisible elementor-widget elementor-widget-rt-working-process\" data-id=\"8291e3b\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"rt-working-process.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"working-process-one dynamic \">\n\t\t\t\t\t\t\t\t\t<div class=\"left\">\n\t\t\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"52\" height=\"52\" viewBox=\"0 0 52 52\" fill=\"none\"><path d=\"M18.0536 12.2099C17.9042 12.6697 18.0512 13.1625 18.428 13.4654L21.7831 16.1621L20.6538 20.3159C20.5271 20.7823 20.6978 21.2673 21.0891 21.5519C21.4805 21.8359 21.9943 21.8484 22.3988 21.5837L26.0003 19.2262L29.6018 21.5838C29.796 21.7109 30.0152 21.774 30.2341 21.774C30.4713 21.774 30.7081 21.6998 30.9113 21.5519C31.3028 21.2677 31.4736 20.7823 31.3466 20.3159L30.2173 16.1622L33.5722 13.4656C33.9493 13.1628 34.0963 12.6699 33.9468 12.2099C33.7974 11.7498 33.3888 11.4375 32.9058 11.4142L28.6065 11.2046L27.0786 7.18045C26.9071 6.7284 26.4837 6.43621 26.0002 6.43621C25.5166 6.43621 25.0932 6.7283 24.9218 7.18035L23.3938 11.2047L19.0948 11.4142C18.6116 11.4375 18.203 11.7498 18.0536 12.2099ZM23.7812 12.8126C24.2394 12.7902 24.6407 12.4987 24.8033 12.0699L26 8.91788L27.1968 12.0702C27.3597 12.4989 27.7611 12.7902 28.2189 12.8126L31.5864 12.9768L28.9584 15.089C28.6008 15.3765 28.4477 15.8483 28.568 16.2907L29.4525 19.5441L26.6315 17.6974C26.4397 17.5719 26.2198 17.5091 25.9999 17.5091C25.7801 17.5091 25.56 17.572 25.368 17.6975L22.5473 19.5441L23.4318 16.2909C23.5522 15.8482 23.399 15.3763 23.0413 15.089L20.4134 12.9769L23.7812 12.8126ZM25.1876 3.79416V0.812498C25.1876 0.363796 25.5514 0 26 0C26.4487 0 26.8125 0.363796 26.8125 0.812498V3.79416C26.8125 4.24287 26.4487 4.60666 26 4.60666C25.5514 4.60666 25.1876 4.24287 25.1876 3.79416ZM30.1355 8.60801C29.8353 8.27459 29.8622 7.76078 30.1956 7.46056L33.5181 4.46874C33.8517 4.16842 34.3654 4.19534 34.6657 4.52887C34.9659 4.8623 34.939 5.3761 34.6055 5.67632L31.2829 8.66814C31.1276 8.80799 30.9332 8.87685 30.7395 8.87685C30.5173 8.87685 30.2959 8.78626 30.1355 8.60801ZM17.3344 4.52887C17.6346 4.19534 18.1483 4.16842 18.482 4.46874L21.8046 7.46056C22.138 7.76078 22.1649 8.27459 21.8647 8.60801C21.7043 8.78615 21.4829 8.87685 21.2606 8.87685C21.067 8.87685 20.8726 8.80799 20.7172 8.66814L17.3946 5.67632C17.061 5.3761 17.0342 4.8623 17.3344 4.52887ZM36.4236 13.4654L39.7786 16.1621L38.6494 20.3159C38.5226 20.7823 38.6933 21.2673 39.0847 21.5519C39.4758 21.8359 39.9897 21.8483 40.3944 21.5837L43.9958 19.2262L47.5973 21.5838C47.7915 21.7109 48.0108 21.774 48.2296 21.774C48.4669 21.774 48.7036 21.6998 48.9069 21.5519C49.2982 21.2679 49.469 20.7827 49.3421 20.3159L48.2129 16.1622L51.5677 13.4656C51.9447 13.1629 52.0918 12.67 51.9423 12.2099C51.7929 11.7498 51.3842 11.4375 50.9014 11.4142L46.602 11.2046L45.0743 7.18045C44.9027 6.7284 44.4793 6.43621 43.9958 6.43621C43.5122 6.43621 43.0888 6.7283 42.9172 7.18035L41.3895 11.2046L37.0904 11.4141C36.6072 11.4374 36.1985 11.7498 36.0491 12.2099C35.8996 12.6699 36.0467 13.1628 36.4236 13.4654ZM41.7766 12.8126C42.235 12.7902 42.6363 12.4987 42.799 12.0698L43.9957 8.91778L45.1923 12.0697C45.3551 12.4987 45.7565 12.7902 46.2146 12.8125L49.582 12.9767L46.9544 15.0887C46.5966 15.3761 46.4432 15.848 46.5637 16.2906L47.4481 19.544L44.6272 17.6973C44.4353 17.5718 44.2154 17.509 43.9955 17.509C43.7755 17.509 43.5555 17.5719 43.3637 17.6974L40.543 19.544L41.4274 16.2908C41.5478 15.8483 41.3946 15.3765 41.0369 15.0889L38.4091 12.9767L41.7766 12.8126ZM0.43227 13.4654L3.78731 16.1621L2.65806 20.3159C2.53132 20.7823 2.70204 21.2673 3.09335 21.5519C3.48476 21.8359 3.99856 21.8484 4.40307 21.5837L8.0045 19.2262L11.606 21.5838C11.8002 21.7109 12.0195 21.774 12.2383 21.774C12.4756 21.774 12.7123 21.6998 12.9155 21.5519C13.3069 21.2679 13.4777 20.7827 13.3508 20.3159L12.2216 16.1622L15.5764 13.4656C15.9532 13.1631 16.1004 12.6703 15.951 12.2094C15.8013 11.7496 15.3926 11.4374 14.9101 11.4141L10.6107 11.2045L9.08297 7.18045C8.91143 6.7284 8.48803 6.43621 8.0045 6.43621C7.52087 6.43621 7.09746 6.7283 6.92593 7.18035L5.39816 11.2046L1.09911 11.4141C0.615993 11.4374 0.207315 11.7498 0.0580212 12.2094C-0.0917801 12.6696 0.0551775 13.1627 0.43227 13.4654ZM5.78531 12.8126C6.24365 12.7902 6.64501 12.4987 6.80771 12.0698L8.0044 8.91778L9.20098 12.0697C9.36378 12.4987 9.76515 12.7902 10.2233 12.8125L13.5907 12.9767L10.963 15.0887C10.6053 15.3761 10.4519 15.848 10.5723 16.2906L11.4568 19.544L8.6359 17.6973C8.44395 17.5718 8.22407 17.509 8.00419 17.509C7.78421 17.509 7.56423 17.5719 7.37239 17.6974L4.55165 19.544L5.43614 16.2908C5.55649 15.8483 5.40334 15.3765 5.04564 15.0889L2.41777 12.9767L5.78531 12.8126ZM51.8716 43.1572C51.2999 41.311 50.129 39.6533 48.5744 38.4892C47.8302 37.9319 47.0198 37.4978 46.1648 37.1905C47.3501 36.2602 48.1139 34.816 48.1139 33.1957C48.1139 30.3961 45.8362 28.1184 43.0367 28.1184C40.2371 28.1184 37.9594 30.3961 37.9594 33.1957C37.9594 34.814 38.7213 36.2568 39.9043 37.1872C38.3188 37.7531 36.9142 38.7474 35.8386 40.0872C35.3359 39.3839 34.756 38.7307 34.104 38.1411C32.7905 36.9531 31.2489 36.0807 29.5887 35.5651C31.3492 34.3979 32.5131 32.3995 32.5131 30.1335C32.5131 26.5423 29.5913 23.6206 26.0002 23.6206C22.409 23.6206 19.4872 26.5423 19.4872 30.1335C19.4872 32.3995 20.651 34.3979 22.4115 35.5651C20.7512 36.0806 19.2096 36.9531 17.8961 38.1411C17.2441 38.7307 16.6642 39.3839 16.1616 40.0872C15.0861 38.7472 13.6815 37.7529 12.096 37.1869C13.2788 36.2565 14.0408 34.8137 14.0408 33.1954C14.0408 30.3958 11.7631 28.1181 8.96363 28.1181C6.16402 28.1181 3.88633 30.3958 3.88633 33.1954C3.88633 34.8156 4.65007 36.2599 5.83527 37.1902C4.98034 37.4975 4.16989 37.9316 3.42555 38.4889C1.87097 39.6529 0.700085 41.3107 0.128402 43.1568C-0.135756 44.0095 0.0105925 44.8749 0.540432 45.5938C1.07017 46.3124 1.85361 46.7081 2.74632 46.7081H13.9782V48.1745C13.9782 50.2839 15.6942 52 17.8036 52H34.1965C36.3058 52 38.0219 50.2839 38.022 48.1745V46.7085H49.2538C50.1466 46.7085 50.93 46.3127 51.4597 45.5942C51.9894 44.8753 52.1358 44.0098 51.8716 43.1572ZM43.0367 29.7434C44.9402 29.7434 46.4889 31.2922 46.4889 33.1957C46.4889 35.0994 44.9402 36.6481 43.0367 36.6481C41.133 36.6481 39.5843 35.0994 39.5843 33.1957C39.5843 31.2922 41.133 29.7434 43.0367 29.7434ZM21.1122 30.1335C21.1122 27.4383 23.3049 25.2455 26.0002 25.2455C28.6954 25.2455 30.8881 27.4383 30.8881 30.1335C30.8881 32.828 28.6968 35.0201 26.0028 35.0215C26.0019 35.0215 26.0009 35.0215 26 35.0215C25.9992 35.0215 25.9983 35.0215 25.9974 35.0215C23.3034 35.02 21.1122 32.8279 21.1122 30.1335ZM8.96363 29.743C10.8672 29.743 12.4159 31.2918 12.4159 33.1953C12.4159 35.099 10.8672 36.6477 8.96363 36.6477C7.05999 36.6477 5.5113 35.099 5.5113 33.1953C5.5113 31.2918 7.05999 29.743 8.96363 29.743ZM14.0837 45.083H2.74642C2.37248 45.083 2.07044 44.9305 1.84853 44.6294C1.62652 44.3284 1.57015 43.9947 1.68075 43.6375C2.67441 40.4286 5.60128 38.2727 8.96363 38.2727C11.507 38.2727 13.8239 39.5016 15.2489 41.5819C14.6855 42.6764 14.291 43.856 14.0837 45.083ZM36.3971 48.1744C36.397 49.3877 35.4098 50.3749 34.1965 50.3749H17.8036C16.5903 50.3749 15.6031 49.3877 15.6031 48.1744V45.9397C16.1914 40.6393 20.6523 36.6478 25.9974 36.6465C25.9983 36.6465 25.9992 36.6466 26.0002 36.6466C26.0011 36.6466 26.002 36.6465 26.0028 36.6465C31.3478 36.6479 35.8086 40.6393 36.3971 45.9397V48.1744ZM50.1517 44.6299C49.9298 44.9309 49.6278 45.0834 49.2538 45.0834H37.9166C37.7092 43.8563 37.3147 42.6767 36.7514 41.5821C38.1765 39.5019 40.4933 38.2731 43.0366 38.2731C46.3989 38.2731 49.3258 40.4291 50.3195 43.638C50.43 43.995 50.3736 44.3287 50.1517 44.6299Z\" fill=\"white\"><\/path><\/svg>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"inner-content\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"number-main\">\n\t\t\t\t\t\t\t<span class=\"number\">01<\/span>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"title\">Client Discovery<\/h3>\n\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"des\">Client Discovery is the foundation of every successful project. <\/p> \n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c0ce3a1 elementor-invisible elementor-widget elementor-widget-rt-working-process\" data-id=\"c0ce3a1\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:300}\" data-widget_type=\"rt-working-process.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"working-process-one dynamic \">\n\t\t\t\t\t\t\t\t\t<div class=\"left\">\n\t\t\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"52\" height=\"56\" viewBox=\"0 0 52 56\" fill=\"none\"><path d=\"M0.912279 19.8709C0.670328 19.8709 0.438286 19.9661 0.2672 20.1355C0.0961148 20.3049 0 20.5346 0 20.7742V24.3871C0 24.6266 0.0961148 24.8564 0.2672 25.0257C0.438286 25.1951 0.670328 25.2903 0.912279 25.2903H2.90139C3.18748 26.5178 3.6619 27.6946 4.30813 28.7798L2.09174 30.9742C2.00702 31.058 1.93982 31.1576 1.89397 31.2672C1.84812 31.3768 1.82453 31.4942 1.82453 31.6129C1.82453 31.7315 1.84812 31.8489 1.89397 31.9585C1.93982 32.0681 2.00702 32.1677 2.09174 32.2516L4.82858 34.9612C4.9133 35.0451 5.01387 35.1116 5.12455 35.157C5.23524 35.2024 5.35387 35.2258 5.47368 35.2258C5.59348 35.2258 5.71212 35.2024 5.8228 35.157C5.93349 35.1116 6.03406 35.0451 6.11877 34.9612L8.33516 32.7668C9.43121 33.4067 10.6198 33.8764 11.8596 34.1596V37.0322C11.8596 37.2718 11.9557 37.5015 12.1268 37.6709C12.2979 37.8403 12.53 37.9354 12.7719 37.9354H15.9706C16.5549 40.1793 17.6759 42.2511 19.2389 43.9758C20.8019 45.7006 22.7611 47.0277 24.9511 47.8452C27.1411 48.6628 29.4976 48.9466 31.8216 48.6729C34.1457 48.3992 36.3692 47.5759 38.3043 46.2725L47.3278 55.2063C47.582 55.458 47.8837 55.6576 48.2157 55.7937C48.5478 55.9299 48.9037 56 49.2631 56C49.6225 56 49.9784 55.9299 50.3105 55.7937C50.6425 55.6576 50.9442 55.458 51.1984 55.2063C51.4525 54.9547 51.6541 54.656 51.7917 54.3272C51.9292 53.9985 52 53.6461 52 53.2903C52 52.9344 51.9292 52.582 51.7917 52.2533C51.6541 51.9245 51.4525 51.6258 51.1984 51.3742L42.1749 42.4403C44.1754 39.5313 45.0329 35.9987 44.586 32.5073C44.1392 29.016 42.4187 25.8068 39.7486 23.4838H41.0526C41.2945 23.4838 41.5266 23.3887 41.6977 23.2193C41.8687 23.0499 41.9649 22.8202 41.9649 22.5806V19.1326C42.1447 18.6606 44.7017 11.9366 44.7017 11.7419C44.7017 9.75573 44.136 8.18863 43.0204 7.08399C41.9048 5.97935 40.3218 5.41935 38.3157 5.41935C36.3096 5.41935 34.7268 5.97946 33.6111 7.08399C32.4954 8.18852 31.9298 9.75573 31.9298 11.7419C31.9298 11.8502 34.6666 19.1314 34.6666 19.1314V20.5943C33.1948 20.1141 31.6549 19.8699 30.1052 19.8709H26.2916C26.0055 18.6434 25.531 17.4666 24.8848 16.3814L27.1012 14.1871C27.1859 14.1032 27.2531 14.0036 27.299 13.894C27.3448 13.7844 27.3684 13.667 27.3684 13.5484C27.3684 13.4298 27.3448 13.3123 27.299 13.2027C27.2531 13.0931 27.1859 12.9936 27.1012 12.9097L24.3644 10.2C24.2796 10.1161 24.1791 10.0496 24.0684 10.0042C23.9577 9.9588 23.8391 9.93544 23.7193 9.93544C23.5995 9.93544 23.4808 9.9588 23.3701 10.0042C23.2595 10.0496 23.1589 10.1161 23.0742 10.2L20.8578 12.3944C19.7617 11.7546 18.5731 11.2849 17.3333 11.0016V8.12902C17.3333 7.88947 17.2372 7.65973 17.0661 7.49035C16.895 7.32096 16.663 7.2258 16.421 7.2258H12.7719C12.53 7.2258 12.2979 7.32096 12.1268 7.49035C11.9557 7.65973 11.8596 7.88947 11.8596 8.12902V11.0016C10.6198 11.2849 9.43121 11.7546 8.33516 12.3944L6.11877 10.2C6.03406 10.1161 5.93349 10.0496 5.8228 10.0042C5.71212 9.9588 5.59348 9.93544 5.47368 9.93544C5.35387 9.93544 5.23524 9.9588 5.12455 10.0042C5.01387 10.0496 4.9133 10.1161 4.82858 10.2L2.09174 12.9097C2.00702 12.9936 1.93982 13.0931 1.89397 13.2027C1.84812 13.3123 1.82453 13.4298 1.82453 13.5484C1.82453 13.667 1.84812 13.7844 1.89397 13.894C1.93982 14.0036 2.00702 14.1032 2.09174 14.1871L4.30813 16.3814C3.6619 17.4666 3.18748 18.6434 2.90139 19.8709H0.912279ZM49.9082 52.6517C49.9949 52.7351 50.0641 52.8348 50.1115 52.9449C50.159 53.055 50.184 53.1733 50.1848 53.293C50.1857 53.4128 50.1625 53.5315 50.1167 53.6422C50.0708 53.753 50.0031 53.8536 49.9176 53.9383C49.8321 54.0229 49.7305 54.0899 49.6186 54.1353C49.5067 54.1807 49.3868 54.2037 49.2659 54.2028C49.1449 54.2019 49.0254 54.1772 48.9142 54.1302C48.803 54.0832 48.7024 54.0147 48.6181 53.9288L39.7558 45.1547C40.212 44.7557 40.6429 44.3292 41.0458 43.8774L49.9082 52.6517ZM33.7558 11.5821C33.8099 8.69117 35.3434 7.2258 38.3157 7.2258C41.292 7.2258 42.8254 8.69467 42.8758 11.5926C42.6193 12.29 41.3726 15.5697 40.4218 18.0645H36.211L33.7558 11.5821ZM36.4912 19.8709H40.1403V21.6774H37.1649C36.9438 21.5559 36.7192 21.4399 36.4912 21.3293V19.8709ZM42.8771 34.3225C42.8771 36.8231 42.1283 39.2676 40.7253 41.3469C39.3223 43.4262 37.3281 45.047 34.9948 46.0043C32.6616 46.9616 30.094 47.2126 27.6168 46.7253C25.1395 46.2381 22.8638 45.0347 21.0772 43.2671C19.2907 41.4995 18.0736 39.2472 17.5798 36.7948C17.086 34.3425 17.3377 31.8002 18.303 29.4895C19.2683 27.1787 20.904 25.2032 23.0031 23.8127C25.1023 22.4222 27.5708 21.6791 30.0964 21.6774H30.1052C33.4914 21.6812 36.7377 23.0147 39.1321 25.3853C41.5265 27.7559 42.8733 30.97 42.8771 34.3225ZM14.5965 27.0967C13.6943 27.0967 12.8124 26.8319 12.0623 26.3356C11.3122 25.8394 10.7275 25.1341 10.3823 24.3089C10.037 23.4837 9.94672 22.5756 10.1227 21.6996C10.2987 20.8235 10.7332 20.0188 11.3711 19.3872C12.009 18.7556 12.8218 18.3255 13.7066 18.1513C14.5914 17.977 15.5086 18.0664 16.342 18.4083C17.1755 18.7501 17.8879 19.3289 18.3891 20.0716C18.8903 20.8143 19.1579 21.6874 19.1579 22.5806C19.1565 23.778 18.6755 24.9259 17.8204 25.7725C16.9652 26.6192 15.8058 27.0954 14.5965 27.0967ZM4.54897 20.9229C4.79965 19.4376 5.37007 18.0231 6.22152 16.7754C6.34429 16.6014 6.40129 16.3903 6.38252 16.1789C6.36376 15.9675 6.27042 15.7694 6.11889 15.6194L4.02692 13.5484L5.47368 12.116L7.56542 14.1871C7.71698 14.3371 7.91706 14.4295 8.13056 14.4481C8.34406 14.4667 8.55735 14.4102 8.73302 14.2887C9.99329 13.4457 11.422 12.8809 12.9221 12.6327C13.135 12.5975 13.3285 12.4887 13.468 12.3256C13.6076 12.1625 13.6842 11.9557 13.6842 11.7419V9.03225H15.5088V11.7419C15.5087 11.9557 15.5853 12.1625 15.7249 12.3257C15.8644 12.4888 16.0579 12.5976 16.2708 12.6328C17.771 12.881 19.1996 13.4458 20.4599 14.2888C20.6356 14.4103 20.8489 14.4668 21.0624 14.4482C21.2759 14.4296 21.476 14.3372 21.6275 14.1872L23.7193 12.116L25.166 13.5484L23.0742 15.6194C22.9226 15.7694 22.8293 15.9675 22.8105 16.1789C22.7918 16.3903 22.8488 16.6014 22.9715 16.7754C23.8226 18.0226 24.3929 19.4364 24.6437 20.9209C23.3168 21.4535 22.0762 22.1763 20.9617 23.0661C20.9741 22.9054 20.9824 22.7438 20.9824 22.5801C20.983 21.2369 20.5517 19.9285 19.7511 18.8442C18.9504 17.76 17.822 16.9562 16.5291 16.5493C15.2363 16.1424 13.8462 16.1535 12.5602 16.5811C11.2741 17.0086 10.1589 17.8303 9.3761 18.9272C8.59326 20.0242 8.18342 21.3393 8.20592 22.6823C8.22843 24.0252 8.68212 25.3262 9.50128 26.3968C10.3205 27.4674 11.4626 28.2521 12.7622 28.6371C14.0619 29.0222 15.4516 28.9876 16.7301 28.5385C15.9226 30.3619 15.5067 32.3316 15.5088 34.3225C15.5089 34.9264 15.5469 35.5298 15.6228 36.129H13.6842V33.4193C13.6842 33.2055 13.6076 32.9987 13.4681 32.8356C13.3285 32.6724 13.1351 32.5636 12.9221 32.5284C11.422 32.2802 9.99329 31.7154 8.73302 30.8724C8.55735 30.7509 8.34406 30.6945 8.13056 30.713C7.91706 30.7316 7.71698 30.824 7.56542 30.9741L5.47368 33.0453L4.02692 31.6129L6.11877 29.5419C6.27031 29.3918 6.36364 29.1937 6.38241 28.9824C6.40118 28.771 6.34417 28.5598 6.2214 28.3859C5.36995 27.1381 4.79954 25.7236 4.54885 24.2384C4.51331 24.0275 4.4034 23.836 4.23865 23.6979C4.07391 23.5597 3.86502 23.4839 3.64912 23.4838H1.82456V21.6774H3.64912C3.86504 21.6774 4.07396 21.6016 4.23872 21.4634C4.40349 21.3253 4.51342 21.1337 4.54897 20.9229Z\" fill=\"white\"><\/path><path d=\"M28.377 5.01538C28.2688 5.22963 28.251 5.47766 28.3275 5.70491C28.404 5.93217 28.5685 6.12003 28.7849 6.22717L30.6095 7.13039C30.7167 7.18454 30.8338 7.21713 30.9538 7.22628C31.0739 7.23543 31.1946 7.22097 31.3089 7.18372C31.4233 7.14647 31.5291 7.08718 31.6202 7.00925C31.7113 6.93133 31.786 6.83632 31.8398 6.7297C31.8937 6.62308 31.9257 6.50697 31.934 6.38805C31.9423 6.26912 31.9267 6.14975 31.8882 6.03681C31.8497 5.92386 31.789 5.81959 31.7096 5.72999C31.6302 5.64039 31.5336 5.56723 31.4255 5.51475L29.601 4.61153C29.3846 4.5044 29.134 4.48676 28.9045 4.56249C28.675 4.63823 28.4852 4.80114 28.377 5.01538Z\" fill=\"white\"><\/path><path d=\"M37.4035 0.903225V2.70967C37.4035 2.94922 37.4996 3.17896 37.6707 3.34835C37.8417 3.51774 38.0738 3.6129 38.3157 3.6129C38.5577 3.6129 38.7897 3.51774 38.9608 3.34835C39.1319 3.17896 39.228 2.94922 39.228 2.70967V0.903225C39.228 0.663675 39.1319 0.433936 38.9608 0.264548C38.7897 0.0951609 38.5577 0 38.3157 0C38.0738 0 37.8417 0.0951609 37.6707 0.264548C37.4996 0.433936 37.4035 0.663675 37.4035 0.903225Z\" fill=\"white\"><\/path><path d=\"M32.434 0.998628C32.2177 1.10577 32.0531 1.29363 31.9766 1.52088C31.9001 1.74814 31.9179 1.99617 32.0261 2.21042L32.9384 4.01687C32.9914 4.1239 33.0653 4.21948 33.1558 4.2981C33.2463 4.37673 33.3516 4.43684 33.4657 4.47497C33.5798 4.5131 33.7004 4.52849 33.8205 4.52027C33.9406 4.51204 34.0579 4.48036 34.1656 4.42704C34.2732 4.37373 34.3692 4.29983 34.4479 4.20962C34.5266 4.11941 34.5865 4.01467 34.6241 3.90143C34.6617 3.78819 34.6764 3.6687 34.6671 3.54985C34.6579 3.431 34.625 3.31513 34.5703 3.20893L33.658 1.40248C33.5498 1.18824 33.36 1.02533 33.1305 0.949596C32.901 0.873859 32.6504 0.891497 32.434 0.998628Z\" fill=\"white\"><\/path><path d=\"M42.9735 1.40248L42.0612 3.20893C42.0065 3.31513 41.9736 3.431 41.9644 3.54985C41.9551 3.6687 41.9697 3.78819 42.0074 3.90143C42.045 4.01467 42.1049 4.11941 42.1836 4.20962C42.2623 4.29983 42.3582 4.37373 42.4659 4.42704C42.5736 4.48036 42.6909 4.51204 42.811 4.52027C42.9311 4.52849 43.0517 4.5131 43.1658 4.47497C43.2798 4.43684 43.3852 4.37673 43.4757 4.2981C43.5662 4.21948 43.64 4.1239 43.6931 4.01687L44.6053 2.21042C44.66 2.10422 44.6929 1.98835 44.7022 1.8695C44.7114 1.75064 44.6968 1.63115 44.6592 1.51792C44.6216 1.40468 44.5617 1.29994 44.483 1.20973C44.4043 1.11951 44.3083 1.04562 44.2006 0.992304C44.0929 0.938988 43.9757 0.907304 43.8555 0.899078C43.7354 0.890853 43.6149 0.90625 43.5008 0.94438C43.3867 0.982511 43.2814 1.04262 43.1909 1.12124C43.1004 1.19987 43.0265 1.29545 42.9735 1.40248Z\" fill=\"white\"><\/path><path d=\"M47.0305 4.61153L45.206 5.51475C45.0979 5.56723 45.0013 5.64039 44.9219 5.72999C44.8425 5.81959 44.7818 5.92386 44.7433 6.03681C44.7048 6.14975 44.6892 6.26912 44.6975 6.38805C44.7058 6.50697 44.7378 6.62308 44.7917 6.7297C44.8455 6.83632 44.9202 6.93133 45.0113 7.00925C45.1024 7.08718 45.2082 7.14647 45.3225 7.18372C45.4369 7.22097 45.5576 7.23543 45.6777 7.22628C45.7977 7.21713 45.9147 7.18454 46.022 7.13039L47.8465 6.22717C47.9547 6.17469 48.0512 6.10154 48.1306 6.01193C48.21 5.92233 48.2707 5.81806 48.3092 5.70511C48.3478 5.59217 48.3633 5.4728 48.355 5.35388C48.3467 5.23495 48.3147 5.11884 48.2608 5.01222C48.207 4.9056 48.1324 4.81059 48.0412 4.73267C47.9501 4.65475 47.8443 4.59545 47.73 4.5582C47.6156 4.52095 47.4949 4.50649 47.3749 4.51564C47.2548 4.52479 47.1378 4.55738 47.0305 4.61153Z\" fill=\"white\"><\/path><path d=\"M19.1579 34.3225C19.1579 36.4662 19.7999 38.5618 21.0028 40.3442C22.2057 42.1266 23.9155 43.5158 25.9159 44.3362C27.9162 45.1565 30.1174 45.3712 32.2409 44.953C34.3645 44.5348 36.3152 43.5025 37.8462 41.9867C39.3772 40.4708 40.4198 38.5396 40.8422 36.4371C41.2646 34.3346 41.0478 32.1553 40.2193 30.1747C39.3907 28.1942 37.9875 26.5015 36.1872 25.3105C34.387 24.1195 32.2704 23.4838 30.1052 23.4838C27.2028 23.4871 24.4202 24.63 22.3679 26.662C20.3156 28.6939 19.1611 31.4489 19.1579 34.3225ZM39.228 34.3225C39.228 36.1089 38.693 37.8552 37.6906 39.3406C36.6881 40.8259 35.2633 41.9836 33.5964 42.6672C31.9294 43.3509 30.0951 43.5297 28.3255 43.1812C26.5558 42.8327 24.9303 41.9725 23.6544 40.7093C22.3786 39.4461 21.5097 37.8367 21.1577 36.0846C20.8057 34.3326 20.9864 32.5165 21.6769 30.866C22.3673 29.2156 23.5366 27.805 25.0369 26.8125C26.5371 25.82 28.3009 25.2903 30.1052 25.2903C32.5239 25.293 34.8427 26.2455 36.553 27.9388C38.2632 29.6321 39.2253 31.9279 39.228 34.3225Z\" fill=\"white\"><\/path><path d=\"M24.6315 34.3225C24.6315 34.083 24.5354 33.8532 24.3643 33.6839C24.1933 33.5145 23.9612 33.4193 23.7193 33.4193C23.4773 33.4193 23.2453 33.5145 23.0742 33.6839C22.9031 33.8532 22.807 34.083 22.807 34.3225C22.8092 36.2383 23.5788 38.0749 24.947 39.4296C26.3152 40.7842 28.1703 41.5462 30.1052 41.5483C30.3472 41.5483 30.5792 41.4532 30.7503 41.2838C30.9214 41.1144 31.0175 40.8847 31.0175 40.6451C31.0175 40.4056 30.9214 40.1758 30.7503 40.0064C30.5792 39.837 30.3472 39.7419 30.1052 39.7419C28.654 39.7403 27.2627 39.1688 26.2365 38.1528C25.2104 37.1369 24.6331 35.7594 24.6315 34.3225Z\" fill=\"white\"><\/path><\/svg>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"inner-content\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"number-main\">\n\t\t\t\t\t\t\t<span class=\"number\">02<\/span>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"title\">Research &amp; Analysis<\/h3>\n\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"des\">Research &amp; Analysis phase, we dive deep into understanding your market.<\/p> \n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9004e02 elementor-invisible elementor-widget elementor-widget-rt-working-process\" data-id=\"9004e02\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:500}\" data-widget_type=\"rt-working-process.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"working-process-one dynamic \">\n\t\t\t\t\t\t\t\t\t<div class=\"left\">\n\t\t\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"52\" height=\"50\" viewBox=\"0 0 52 50\" fill=\"none\"><path d=\"M6.95259 4.36346C6.6972 4.36346 6.45227 4.46585 6.27168 4.6481C6.09108 4.83035 5.98963 5.07754 5.98963 5.33528C5.98963 5.59302 6.09108 5.8402 6.27168 6.02246C6.45227 6.20471 6.6972 6.30709 6.95259 6.30709C7.20799 6.30709 7.45292 6.20471 7.63351 6.02246C7.8141 5.8402 7.91556 5.59302 7.91556 5.33528C7.91556 5.07754 7.8141 4.83035 7.63351 4.6481C7.45292 4.46585 7.20799 4.36346 6.95259 4.36346Z\" fill=\"white\"><\/path><path d=\"M10.4867 4.36346C10.2962 4.36346 10.11 4.42045 9.95167 4.52724C9.79331 4.63402 9.66989 4.7858 9.597 4.96338C9.52412 5.14095 9.50505 5.33636 9.54221 5.52487C9.57936 5.71338 9.67108 5.88654 9.80575 6.02246C9.94042 6.15837 10.112 6.25092 10.2988 6.28842C10.4856 6.32592 10.6792 6.30667 10.8552 6.23312C11.0311 6.15956 11.1815 6.035 11.2873 5.87519C11.3932 5.71537 11.4496 5.52748 11.4496 5.33528C11.4496 5.07754 11.3482 4.83035 11.1676 4.6481C10.987 4.46585 10.7421 4.36346 10.4867 4.36346Z\" fill=\"white\"><\/path><path d=\"M14.0207 4.36346C13.8303 4.36346 13.6441 4.42045 13.4857 4.52724C13.3274 4.63402 13.204 4.7858 13.1311 4.96338C13.0582 5.14095 13.0391 5.33636 13.0763 5.52487C13.1134 5.71338 13.2052 5.88654 13.3398 6.02246C13.4745 6.15837 13.6461 6.25092 13.8329 6.28842C14.0197 6.32592 14.2133 6.30667 14.3893 6.23312C14.5652 6.15956 14.7156 6.035 14.8214 5.87519C14.9272 5.71537 14.9837 5.52748 14.9837 5.33528C14.9837 5.07754 14.8823 4.83035 14.7017 4.6481C14.5211 4.46585 14.2761 4.36346 14.0207 4.36346Z\" fill=\"white\"><\/path><path d=\"M38.7015 50H42.2933C42.857 49.9974 43.3968 49.7703 43.7954 49.3681C44.1939 48.9659 44.4189 48.4211 44.4215 47.8523V45.967H46.9156C48.2633 45.9644 49.555 45.423 50.508 44.4612C51.461 43.4995 51.9975 42.1959 52 40.8358V5.1312C52 3.77032 51.4643 2.46518 50.5108 1.50289C49.5573 0.540606 48.264 0 46.9156 0H5.08444C3.73597 0 2.44272 0.540606 1.4892 1.50289C0.535681 2.46518 0 3.77032 0 5.1312V40.8358C0.00254523 42.1959 0.539043 43.4995 1.49201 44.4612C2.44498 45.423 3.73675 45.9644 5.08444 45.967H7.57852V47.8523C7.58105 48.4211 7.80608 48.9659 8.20464 49.3681C8.6032 49.7703 9.14303 49.9974 9.70667 50H13.2985C13.5801 49.9999 13.8589 49.9431 14.1184 49.8329C14.378 49.7228 14.6133 49.5615 14.8104 49.3586C15.0035 49.1597 15.1557 48.9242 15.2582 48.6657C15.3606 48.4072 15.4114 48.1307 15.4074 47.8523V45.967H17.2274V47.8523C17.2299 48.4194 17.4536 48.9628 17.8501 49.3647C18.2466 49.7667 18.784 49.9949 19.3459 50H22.9474C23.511 49.9974 24.0509 49.7703 24.4494 49.3681C24.848 48.9659 25.073 48.4211 25.0756 47.8523V45.967H26.8859V47.8523C26.8885 48.4211 27.1135 48.9659 27.512 49.3681C27.9106 49.7703 28.4504 49.9974 29.0141 50H32.6156C32.897 49.9988 33.1754 49.9415 33.4349 49.8314C33.6943 49.7214 33.9296 49.5607 34.1274 49.3586C34.3236 49.1615 34.4784 48.9266 34.5827 48.6678C34.6869 48.409 34.7384 48.1316 34.7341 47.8523V45.967H36.5926V47.8523C36.5951 48.4178 36.8174 48.9597 37.2119 49.3613C37.6063 49.763 38.1412 49.9924 38.7015 50ZM42.4956 47.8523C42.4956 47.9064 42.4743 47.9583 42.4363 47.9966C42.3984 48.0349 42.347 48.0564 42.2933 48.0564H38.7015C38.6479 48.0564 38.5964 48.0349 38.5585 47.9966C38.5206 47.9583 38.4993 47.9064 38.4993 47.8523V24.8591C38.4993 24.805 38.5206 24.753 38.5585 24.7148C38.5964 24.6765 38.6479 24.655 38.7015 24.655H42.2933C42.347 24.655 42.3984 24.6765 42.4363 24.7148C42.4743 24.753 42.4956 24.805 42.4956 24.8591V47.8523ZM13.4815 47.8523C13.483 47.8779 13.4786 47.9036 13.4685 47.9272C13.4585 47.9508 13.4432 47.9718 13.4237 47.9883C13.4055 48.009 13.3832 48.0256 13.3584 48.0373C13.3336 48.049 13.3066 48.0555 13.2793 48.0564H9.70667C9.65303 48.0564 9.6016 48.0349 9.56367 47.9966C9.52575 47.9583 9.50444 47.9064 9.50444 47.8523V40.5442C9.50444 40.4901 9.52575 40.4382 9.56367 40.3999C9.6016 40.3616 9.65303 40.3401 9.70667 40.3401H13.2985C13.3487 40.345 13.3954 40.3686 13.4292 40.4064C13.4631 40.4441 13.4817 40.4933 13.4815 40.5442V47.8523ZM23.1111 47.8523C23.1111 47.9064 23.0898 47.9583 23.0519 47.9966C23.014 48.0349 22.9625 48.0564 22.9089 48.0564H19.3652C19.3132 48.0539 19.2642 48.0313 19.2284 47.9933C19.1925 47.9553 19.1725 47.9048 19.1726 47.8523V32.2157C19.1713 32.1889 19.1753 32.1621 19.1842 32.1369C19.1932 32.1116 19.2071 32.0884 19.2249 32.0685C19.2428 32.0487 19.2644 32.0326 19.2885 32.0211C19.3126 32.0097 19.3386 32.0032 19.3652 32.0019H22.9667C23.0212 32.0044 23.0726 32.0281 23.1103 32.0679C23.148 32.1077 23.1689 32.1607 23.1689 32.2157L23.1111 47.8523ZM32.7407 47.8523C32.7417 47.902 32.7245 47.9504 32.6926 47.9883C32.6743 48.009 32.6521 48.0256 32.6273 48.0373C32.6025 48.049 32.5755 48.0555 32.5481 48.0564H29.0333C28.9797 48.0564 28.9283 48.0349 28.8903 47.9966C28.8524 47.9583 28.8311 47.9064 28.8311 47.8523V37.036C28.8311 36.9818 28.8524 36.9299 28.8903 36.8917C28.9283 36.8534 28.9797 36.8319 29.0333 36.8319H32.6348C32.6609 36.8318 32.6868 36.8372 32.7108 36.8475C32.7348 36.8579 32.7565 36.8731 32.7745 36.8922C32.7925 36.9113 32.8065 36.9339 32.8156 36.9586C32.8247 36.9833 32.8287 37.0096 32.8274 37.036L32.7407 47.8523ZM34.6667 44.0233V37.036C34.6667 36.468 34.4438 35.9232 34.0468 35.5207C33.6497 35.1182 33.1109 34.8908 32.5481 34.8882H29.0333C28.4697 34.8908 27.9299 35.1179 27.5313 35.5201C27.1327 35.9223 26.9077 36.4671 26.9052 37.036V44.0233H25.0948V32.2157C25.0961 31.9329 25.042 31.6526 24.9356 31.3909C24.8292 31.1292 24.6727 30.8913 24.4749 30.6908C24.2772 30.4903 24.0421 30.3313 23.7833 30.2227C23.5245 30.1142 23.247 30.0583 22.9667 30.0583H19.3652C19.0857 30.0596 18.8092 30.1164 18.5515 30.2255C18.2938 30.3346 18.0599 30.4939 17.8632 30.6942C17.6664 30.8946 17.5108 31.132 17.405 31.3931C17.2992 31.6542 17.2454 31.9337 17.2467 32.2157V44.0233H15.4074V40.5442C15.4049 39.9763 15.1795 39.4325 14.7807 39.0318C14.3819 38.6312 13.842 38.4062 13.2793 38.4062H9.70667C9.14391 38.4062 8.60406 38.6312 8.20523 39.0318C7.8064 39.4325 7.58107 39.9763 7.57852 40.5442V44.0525H5.08444C4.66758 44.0512 4.25507 43.9669 3.87054 43.8045C3.48602 43.642 3.13704 43.4045 2.84362 43.1057C2.5502 42.8069 2.3181 42.4526 2.16062 42.063C2.00315 41.6735 1.92339 41.2565 1.92593 40.8358V5.1312C1.92593 4.2858 2.2587 3.47503 2.85103 2.87725C3.44337 2.27947 4.24675 1.94363 5.08444 1.94363H46.9156C47.7533 1.94363 48.5566 2.27947 49.149 2.87725C49.7413 3.47503 50.0741 4.2858 50.0741 5.1312V40.8358C50.0715 41.6804 49.7379 42.4896 49.1462 43.0869C48.5544 43.6841 47.7525 44.0208 46.9156 44.0233H44.4215V24.8591C44.4215 24.2895 44.1973 23.7432 43.7982 23.3404C43.3991 22.9376 42.8578 22.7114 42.2933 22.7114H38.7015C38.1404 22.7165 37.604 22.945 37.2091 23.3473C36.8141 23.7495 36.5926 24.2928 36.5926 24.8591V44.0233H34.6667Z\" fill=\"white\"><\/path><path d=\"M40.5022 18.8241C41.3843 18.819 42.2289 18.4631 42.8526 17.8336C43.4764 17.2041 43.829 16.3518 43.8341 15.4616C43.8315 14.5706 43.4797 13.7168 42.8554 13.0868C42.2311 12.4568 41.3851 12.1017 40.5022 12.0991C39.6186 12.0991 38.7711 12.4534 38.1462 13.084C37.5214 13.7146 37.1704 14.5698 37.1704 15.4616C37.187 16.1272 37.4055 16.7717 37.7963 17.3081L32.0185 24.5384C31.4151 24.3042 30.7583 24.2474 30.1243 24.3747C29.4902 24.502 28.9049 24.8081 28.4363 25.2575C28.4204 25.2888 28.4011 25.3182 28.3785 25.345L24.3533 23.3333C24.4034 23.1651 24.4388 22.9927 24.4593 22.8183C24.4593 21.9265 24.1082 21.0712 23.4834 20.4406C22.8585 19.81 22.0111 19.4558 21.1274 19.4558C20.2437 19.4558 19.3963 19.81 18.7714 20.4406C18.1466 21.0712 17.7956 21.9265 17.7956 22.8183C17.7975 23.2808 17.8959 23.7378 18.0844 24.1594L13.2215 28.3382C12.701 27.9799 12.0891 27.7808 11.4593 27.7648C10.5789 27.7674 9.73539 28.1214 9.1129 28.7497C8.49041 29.3779 8.13958 30.2292 8.13704 31.1176C8.12949 31.5596 8.21096 31.9985 8.37648 32.4078C8.54201 32.817 8.78815 33.1881 9.1 33.4985C9.56591 33.9662 10.1585 34.2844 10.8031 34.4131C11.4478 34.5418 12.1157 34.4752 12.723 34.2218C13.3302 33.9683 13.8497 33.5393 14.2159 32.9887C14.5822 32.4381 14.779 31.7905 14.7815 31.1273C14.7772 30.6692 14.6822 30.2165 14.5022 29.7959L19.3652 25.6171C19.8814 25.978 20.4901 26.1805 21.1178 26.2002C21.5724 26.1968 22.0214 26.0994 22.4372 25.9138C22.8529 25.7283 23.2265 25.4586 23.5348 25.1215L27.56 27.1234C27.5118 27.2954 27.4764 27.4709 27.4541 27.6482C27.4363 28.1824 27.545 28.7132 27.7711 29.1965C27.9972 29.6799 28.3343 30.1019 28.7543 30.4275C29.1743 30.7531 29.6652 30.973 30.1862 31.0689C30.7072 31.1648 31.2434 31.134 31.7503 30.979C32.2572 30.824 32.7201 30.5492 33.1008 30.1776C33.4814 29.8059 33.7688 29.348 33.9391 28.8419C34.1093 28.3358 34.1576 27.796 34.0798 27.2672C34.002 26.7385 33.8005 26.2361 33.4919 25.8018L39.2119 18.5909C39.6226 18.7533 40.0611 18.8326 40.5022 18.8241ZM12.9037 31.1176C12.8966 31.4817 12.7519 31.8293 12.4993 32.0894C12.2306 32.3478 11.8737 32.492 11.5026 32.492C11.1315 32.492 10.7746 32.3478 10.5059 32.0894C10.2499 31.8316 10.1046 31.4826 10.1015 31.1176C10.1002 30.9317 10.1354 30.7474 10.205 30.5754C10.2746 30.4033 10.3772 30.2468 10.507 30.1149C10.6368 29.983 10.7912 29.8783 10.9612 29.8069C11.1312 29.7355 11.3136 29.6987 11.4978 29.6987C11.8582 29.7079 12.202 29.8536 12.4607 30.1069C12.7134 30.367 12.858 30.7146 12.8652 31.0787L12.9037 31.1176ZM21.1852 24.2371C20.8228 24.2283 20.4778 24.0786 20.2222 23.8192C20.0933 23.6927 19.9903 23.5417 19.9193 23.375C19.8482 23.2082 19.8104 23.0289 19.8081 22.8474C19.8146 22.57 19.9016 22.3005 20.0583 22.0724C20.215 21.8443 20.4345 21.6676 20.6897 21.5642C20.9449 21.4607 21.2246 21.4351 21.4941 21.4905C21.7636 21.5458 22.0111 21.6797 22.2059 21.8756C22.4646 22.1324 22.6133 22.4813 22.62 22.8474C22.6175 23.0341 22.5783 23.2185 22.5046 23.3898C22.4309 23.5611 22.3242 23.7159 22.1907 23.8452C22.0572 23.9745 21.8995 24.0757 21.7269 24.143C21.5543 24.2103 21.3702 24.2423 21.1852 24.2371ZM40.5022 14.0428C40.863 14.05 41.2075 14.196 41.4652 14.4509C41.7205 14.71 41.8686 15.0575 41.8793 15.4227C41.8686 15.788 41.7205 16.1355 41.4652 16.3946C41.1966 16.653 40.8397 16.7972 40.4685 16.7972C40.0974 16.7972 39.7405 16.653 39.4719 16.3946C39.2778 16.1979 39.1451 15.9482 39.0902 15.6762C39.0354 15.4042 39.0607 15.122 39.1632 14.8644C39.2657 14.6069 39.4408 14.3853 39.6668 14.2272C39.8929 14.069 40.1599 13.9813 40.4348 13.9747L40.5022 14.0428ZM32.24 27.6482C32.2335 27.9257 32.1466 28.1951 31.9899 28.4232C31.8332 28.6513 31.6136 28.828 31.3584 28.9315C31.1032 29.0349 30.8235 29.0605 30.554 29.0052C30.2846 28.9498 30.0371 28.8159 29.8422 28.62C29.6774 28.4543 29.5558 28.2498 29.4886 28.025C29.4213 27.8001 29.4104 27.562 29.4568 27.3318C29.5032 27.1017 29.6055 26.8868 29.7545 26.7064C29.9035 26.526 30.0946 26.3857 30.3105 26.2982C30.5265 26.2107 30.7606 26.1786 30.9918 26.2049C31.2231 26.2312 31.4443 26.315 31.6355 26.4488C31.8268 26.5826 31.9821 26.7622 32.0876 26.9716C32.1931 27.1809 32.2455 27.4134 32.24 27.6482Z\" fill=\"white\"><\/path><path d=\"M19.6444 6.30709H43.8533C44.1087 6.30709 44.3537 6.20471 44.5343 6.02246C44.7148 5.8402 44.8163 5.59302 44.8163 5.33528C44.8163 5.07754 44.7148 4.83035 44.5343 4.6481C44.3537 4.46585 44.1087 4.36346 43.8533 4.36346H19.6444C19.3891 4.36346 19.1441 4.46585 18.9635 4.6481C18.7829 4.83035 18.6815 5.07754 18.6815 5.33528C18.6815 5.59302 18.7829 5.8402 18.9635 6.02246C19.1441 6.20471 19.3891 6.30709 19.6444 6.30709Z\" fill=\"white\"><\/path><\/svg>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"inner-content\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"number-main\">\n\t\t\t\t\t\t\t<span class=\"number\">03<\/span>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"title\">Strategy Development<\/h3>\n\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"des\">Based on insights from the research phase, we craft a tailored marketing strategy.<\/p> \n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3d3c950 elementor-invisible elementor-widget elementor-widget-rt-react-image\" data-id=\"3d3c950\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInRight&quot;,&quot;_animation_delay&quot;:200}\" data-widget_type=\"rt-react-image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n        <div class=\"react-image animate-   \">\n                            <img decoding=\"async\" loading=\"lazy\" class=\"react-multi-image      \" src=\"https:\/\/reactheme.com\/products\/wordpress\/invena\/coach\/wp-content\/uploads\/2025\/05\/03-2.webp\" alt=\"\"\/>\n                    <\/div>\n\n               \n    \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3efa638 e-flex e-con-boxed e-con e-parent\" data-id=\"3efa638\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0d62311 elementor-widget elementor-widget-react-heading\" data-id=\"0d62311\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"react-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"react-heading \">\r\n\t\t\t\t<span class=\"sub-text\">faq<\/span><h2 class=\"title  rts-text-anime-style-1\">Frequently Asked Questions <span class=\"stroke_text\"><\/span><\/h2>\t\t\r\n\t\t\t<\/div>\t\r\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f6f79dd e-flex e-con-boxed e-con e-child\" data-id=\"f6f79dd\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-0de9957 e-con-full e-flex e-con e-child\" data-id=\"0de9957\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9bea1b5 elementor-widget elementor-widget-rt-react-image\" data-id=\"9bea1b5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"rt-react-image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n        <div class=\"react-image animate-no   \">\n                            <img decoding=\"async\" loading=\"lazy\" class=\"react-multi-image      \" src=\"https:\/\/reactheme.com\/products\/wordpress\/invena\/coach\/wp-content\/uploads\/2025\/05\/02-6.webp\" alt=\"\"\/>\n                    <\/div>\n\n               \n    \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f62a899 e-con-full e-flex e-con e-child\" data-id=\"f62a899\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-049a7ad elementor-widget__width-initial elementor-widget elementor-widget-n-accordion\" data-id=\"049a7ad\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;n_accordion_animation_duration&quot;:{&quot;unit&quot;:&quot;ms&quot;,&quot;size&quot;:200,&quot;sizes&quot;:[]},&quot;default_state&quot;:&quot;expanded&quot;,&quot;max_items_expended&quot;:&quot;one&quot;}\" data-widget_type=\"nested-accordion.default\">\n\t\t\t\t\t\t\t<div class=\"e-n-accordion\" aria-label=\"Accordion. Open links with Enter or Space, close with Escape, and navigate with Arrow Keys\">\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-4820\" class=\"e-n-accordion-item\" open>\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"1\" tabindex=\"0\" aria-expanded=\"true\" aria-controls=\"e-n-accordion-item-4820\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><h3 class=\"e-n-accordion-item-title-text\"> 01. What services\/products do you offer? <\/h3><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-angle-up\" viewBox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M177 159.7l136 136c9.4 9.4 9.4 24.6 0 33.9l-22.6 22.6c-9.4 9.4-24.6 9.4-33.9 0L160 255.9l-96.4 96.4c-9.4 9.4-24.6 9.4-33.9 0L7 329.7c-9.4-9.4-9.4-24.6 0-33.9l136-136c9.4-9.5 24.6-9.5 34-.1z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-angle-down\" viewBox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M143 352.3L7 216.3c-9.4-9.4-9.4-24.6 0-33.9l22.6-22.6c9.4-9.4 24.6-9.4 33.9 0l96.4 96.4 96.4-96.4c9.4-9.4 24.6-9.4 33.9 0l22.6 22.6c9.4 9.4 9.4 24.6 0 33.9l-136 136c-9.2 9.4-24.4 9.4-33.8 0z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-4820\" class=\"elementor-element elementor-element-39d76e2 e-con-full e-flex e-con e-child\" data-id=\"39d76e2\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-42bb46b elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"42bb46b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Strategic planning, market analysis, and performance optimization. Client Discovery &amp; Research \u2013 In-depth discovery sessions to understand client needs, goals, and challenges.<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-4821\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"2\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-4821\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><h3 class=\"e-n-accordion-item-title-text\"> 02. Where i can find my business growth result? <\/h3><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-angle-up\" viewBox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M177 159.7l136 136c9.4 9.4 9.4 24.6 0 33.9l-22.6 22.6c-9.4 9.4-24.6 9.4-33.9 0L160 255.9l-96.4 96.4c-9.4 9.4-24.6 9.4-33.9 0L7 329.7c-9.4-9.4-9.4-24.6 0-33.9l136-136c9.4-9.5 24.6-9.5 34-.1z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-angle-down\" viewBox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M143 352.3L7 216.3c-9.4-9.4-9.4-24.6 0-33.9l22.6-22.6c9.4-9.4 24.6-9.4 33.9 0l96.4 96.4 96.4-96.4c9.4-9.4 24.6-9.4 33.9 0l22.6 22.6c9.4 9.4 9.4 24.6 0 33.9l-136 136c-9.2 9.4-24.4 9.4-33.8 0z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-4821\" class=\"elementor-element elementor-element-2f58365 e-con-full e-flex e-con e-child\" data-id=\"2f58365\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-53805ed elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"53805ed\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">You can track your business growth results through detailed performance reports and analytics dashboards. We provide insights on key metrics such as website traffic, lead generation.<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-4822\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"3\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-4822\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><h3 class=\"e-n-accordion-item-title-text\"> 03. Did you get any business consultant? <\/h3><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-angle-up\" viewBox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M177 159.7l136 136c9.4 9.4 9.4 24.6 0 33.9l-22.6 22.6c-9.4 9.4-24.6 9.4-33.9 0L160 255.9l-96.4 96.4c-9.4 9.4-24.6 9.4-33.9 0L7 329.7c-9.4-9.4-9.4-24.6 0-33.9l136-136c9.4-9.5 24.6-9.5 34-.1z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-angle-down\" viewBox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M143 352.3L7 216.3c-9.4-9.4-9.4-24.6 0-33.9l22.6-22.6c9.4-9.4 24.6-9.4 33.9 0l96.4 96.4 96.4-96.4c9.4-9.4 24.6-9.4 33.9 0l22.6 22.6c9.4 9.4 9.4 24.6 0 33.9l-136 136c-9.2 9.4-24.4 9.4-33.8 0z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-4822\" class=\"elementor-element elementor-element-6f1585d e-con-full e-flex e-con e-child\" data-id=\"6f1585d\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-fd578e2 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"fd578e2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">\"Yes, our team includes experienced business consultants who specialize in marketing, strategy, and growth planning. They work closely with you to understand your challenges.<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-4823\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"4\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-4823\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><h3 class=\"e-n-accordion-item-title-text\"> 04. Do you need any business invesment policy? <\/h3><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-angle-up\" viewBox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M177 159.7l136 136c9.4 9.4 9.4 24.6 0 33.9l-22.6 22.6c-9.4 9.4-24.6 9.4-33.9 0L160 255.9l-96.4 96.4c-9.4 9.4-24.6 9.4-33.9 0L7 329.7c-9.4-9.4-9.4-24.6 0-33.9l136-136c9.4-9.5 24.6-9.5 34-.1z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-angle-down\" viewBox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M143 352.3L7 216.3c-9.4-9.4-9.4-24.6 0-33.9l22.6-22.6c9.4-9.4 24.6-9.4 33.9 0l96.4 96.4 96.4-96.4c9.4-9.4 24.6-9.4 33.9 0l22.6 22.6c9.4 9.4 9.4 24.6 0 33.9l-136 136c-9.2 9.4-24.4 9.4-33.8 0z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-4823\" class=\"elementor-element elementor-element-fb3614d e-con-full e-flex e-con e-child\" data-id=\"fb3614d\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7bbe807 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"7bbe807\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Yes, having a well-defined business investment policy is essential for sustainable growth. It outlines how funds are allocated, risk management strategies, and expected returns on investment. <\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-4824\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"5\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-4824\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><h3 class=\"e-n-accordion-item-title-text\"> 05. Do you require a business investment plan? <\/h3><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-angle-up\" viewBox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M177 159.7l136 136c9.4 9.4 9.4 24.6 0 33.9l-22.6 22.6c-9.4 9.4-24.6 9.4-33.9 0L160 255.9l-96.4 96.4c-9.4 9.4-24.6 9.4-33.9 0L7 329.7c-9.4-9.4-9.4-24.6 0-33.9l136-136c9.4-9.5 24.6-9.5 34-.1z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-angle-down\" viewBox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M143 352.3L7 216.3c-9.4-9.4-9.4-24.6 0-33.9l22.6-22.6c9.4-9.4 24.6-9.4 33.9 0l96.4 96.4 96.4-96.4c9.4-9.4 24.6-9.4 33.9 0l22.6 22.6c9.4 9.4 9.4 24.6 0 33.9l-136 136c-9.2 9.4-24.4 9.4-33.8 0z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-4824\" class=\"elementor-element elementor-element-8ac0087 e-con-full e-flex e-con e-child\" data-id=\"8ac0087\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-553c7cd elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"553c7cd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">A business investment plan is crucial for outlining how your company will secure, allocate, and manage financial resources to achieve growth objectives. It helps attract investors.<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9195931 e-flex e-con-boxed e-con e-parent\" data-id=\"9195931\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b90c023 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"b90c023\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">Our Trusted Clients<\/span>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9c989f6 elementor-widget__width-inherit elementor-widget elementor-widget-rt-client-logo\" data-id=\"9c989f6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"rt-client-logo.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t       \n            <div id=\"swiper-1\" class=\"swiper rt-all-slider rt-client-logo\" data-loop=\"false\" \n            data-autoplay=\"false\" \n            data-speed=\"900\" \n            data-centered-slides=\"false\" \n            data-autoplay-delay=\"3000\" \n            data-free-mode=\"false\" \n            data-slides-per-view=\"6\" \n            data-space-between=\"\" \n            data-slides-per-view-tablet=\"4\" \n            data-slides-per-view-mobile=\"2\" \n            data-pagination=\"none\" \n            data-navigation=\"false\">\n                <div class=\"swiper-wrapper\">\n                                            <div class=\"swiper-slide\">\n                            <a aria-label=\"Brand Logo\" href=\"#\" class=\"logo \">\n                                <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/reactheme.com\/products\/wordpress\/invena\/coach\/wp-content\/uploads\/2025\/05\/1.webp\" alt=\"\">\n                            <\/a> \n                        <\/div>\n                                                <div class=\"swiper-slide\">\n                            <a aria-label=\"Brand Logo\" href=\"#\" class=\"logo \">\n                                <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/reactheme.com\/products\/wordpress\/invena\/coach\/wp-content\/uploads\/2025\/05\/2.webp\" alt=\"\">\n                            <\/a> \n                        <\/div>\n                                                <div class=\"swiper-slide\">\n                            <a aria-label=\"Brand Logo\" href=\"#\" class=\"logo \">\n                                <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/reactheme.com\/products\/wordpress\/invena\/coach\/wp-content\/uploads\/2025\/05\/3.webp\" alt=\"\">\n                            <\/a> \n                        <\/div>\n                                                <div class=\"swiper-slide\">\n                            <a aria-label=\"Brand Logo\" href=\"#\" class=\"logo \">\n                                <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/reactheme.com\/products\/wordpress\/invena\/coach\/wp-content\/uploads\/2025\/05\/4.webp\" alt=\"\">\n                            <\/a> \n                        <\/div>\n                                                <div class=\"swiper-slide\">\n                            <a aria-label=\"Brand Logo\" href=\"#\" class=\"logo \">\n                                <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/reactheme.com\/products\/wordpress\/invena\/coach\/wp-content\/uploads\/2025\/05\/5.webp\" alt=\"\">\n                            <\/a> \n                        <\/div>\n                                                <div class=\"swiper-slide\">\n                            <a aria-label=\"Brand Logo\" href=\"#\" class=\"logo \">\n                                <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/reactheme.com\/products\/wordpress\/invena\/coach\/wp-content\/uploads\/2025\/05\/6.webp\" alt=\"\">\n                            <\/a> \n                        <\/div>\n                                            \n                <\/div>\n                            <\/div>\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c20674c e-flex e-con-boxed e-con e-child\" data-id=\"c20674c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5a0018f elementor-widget elementor-widget-react-heading\" data-id=\"5a0018f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"react-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"react-heading \">\r\n\t\t\t\t<span class=\"sub-text\">Our Testimonial<\/span><h2 class=\"title  rts-text-anime-style-1\">Our Customer Feedbacks <span class=\"stroke_text\"><\/span><\/h2>\t\t\r\n\t\t\t<\/div>\t\r\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-acb2b66 elementor-widget elementor-widget-rt-testimonial-slider\" data-id=\"acb2b66\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"rt-testimonial-slider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t \r\n\r\n        <div id=\"swiper-6a03d248a3851\"  data-loop=\"true\" \r\n            data-autoplay=\"true\" \r\n            data-speed=\"1200\" \r\n            data-centered-slides=\"false\" \r\n            data-autoplay-delay=\"3000\" \r\n            data-free-mode=\"true\" \r\n            data-slides-per-view=\"2\" \r\n            data-space-between=\"30\" \r\n            data-slides-per-view-tablet=\"1\" \r\n            data-slides-per-view-mobile=\"1\" \r\n            data-pagination=\"fraction\" \r\n            data-navigation=\"true\",\r\n            data-thumbnail-pagination=\"false\",\r\n            data-thumb-slides-per-view=\"\",\r\n            data-thumb-slides-per-view-mobile=\"\"  class=\"swiper rt--slider rt-all-slider testimonial-style2 \">\r\n            <div class=\"swiper-wrapper\">\r\n                <div class=\"swiper-slide\">\r\n    <div class=\"testimonials-slider-two slider_item\">\r\n                    <div class=\"thumbnail\">\r\n                <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/reactheme.com\/products\/wordpress\/invena\/coach\/wp-content\/uploads\/2025\/05\/04-3.webp\" alt=\"\">\r\n            <\/div>\r\n                    <div class=\"inner-content\">\r\n            <div class=\"name-area\">\r\n                                    <h3 class=\"name\">Jonathon Doe<\/h3>\r\n                                        <span class=\"designation\">Finance<\/span>\r\n                           \r\n            <\/div>\r\n                           <p class=\"disc\">\u201cDabus nisl aliquet congue tellus nascetur lectus sagpien mattis arcu dictums augue volutpat felis etiam suspendisse rhoncus mauris dignissim ante\u201d<\/p>\r\n                      \r\n            <div class=\"body-end\">\r\n                                    <a aria-label=\"clients logo\" class=\"client-logo\" href=\"#\">\r\n                        <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/reactheme.com\/products\/wordpress\/invena\/coach\/wp-content\/uploads\/2025\/05\/02-7.webp\" alt=\"\"><\/a>\r\n                                    <div class=\"stars\">\r\n                   <i class=\"rating fas fa-star\"><\/i><i class=\"rating fas fa-star\"><\/i><i class=\"rating fas fa-star\"><\/i><i class=\"rating fas fa-star\"><\/i><i class=\"rating fas fa-star\"><\/i>                <\/div>\r\n            <\/div>\r\n        <\/div>        \r\n    <\/div>   \r\n<\/div>\r\n<div class=\"swiper-slide\">\r\n    <div class=\"testimonials-slider-two slider_item\">\r\n                    <div class=\"thumbnail\">\r\n                <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/reactheme.com\/products\/wordpress\/invena\/coach\/wp-content\/uploads\/2025\/05\/03-3.webp\" alt=\"\">\r\n            <\/div>\r\n                    <div class=\"inner-content\">\r\n            <div class=\"name-area\">\r\n                                    <h3 class=\"name\">David Smith<\/h3>\r\n                                        <span class=\"designation\">Director<\/span>\r\n                           \r\n            <\/div>\r\n                           <p class=\"disc\">As a company director, developing a comprehensive business investment plan is essential to strategically allocate resources, capitalize on growth opportunities.<\/p>\r\n                      \r\n            <div class=\"body-end\">\r\n                                    <a aria-label=\"clients logo\" class=\"client-logo\" href=\"#\">\r\n                        <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/reactheme.com\/products\/wordpress\/invena\/coach\/wp-content\/uploads\/2025\/05\/03-4.webp\" alt=\"\"><\/a>\r\n                                    <div class=\"stars\">\r\n                   <i class=\"rating fas fa-star\"><\/i><i class=\"rating fas fa-star\"><\/i><i class=\"rating fas fa-star\"><\/i><i class=\"rating fas fa-star\"><\/i><i class=\"rating fas fa-star\"><\/i>                <\/div>\r\n            <\/div>\r\n        <\/div>        \r\n    <\/div>   \r\n<\/div>\r\n            <\/div>\r\n                            <div class=\"swiper-navigaiton\">\r\n                    <span class=\"swiper-prev\"><i class=\"rt rt-arrow-left\"><\/i><\/span>\r\n                    <span class=\"swiper-next\"><i class=\"rt rt-arrow-right\"><\/i><\/span>\r\n                <\/div>\r\n                                    <div class=\"swiper-pagination\"><span class=\"swiper-pagination\"><\/span><\/div>\r\n                \t\r\n        <\/div>  \r\n\r\n        <!-- Thumbnail Pagination -->\r\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5a3ca4e e-flex e-con-boxed e-con e-parent\" data-id=\"5a3ca4e\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4b217b2 elementor-widget__width-initial elementor-widget elementor-widget-react-heading\" data-id=\"4b217b2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"react-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"react-heading \">\r\n\t\t\t\t<span class=\"sub-text\">Subscribe Newsletter<\/span><h2 class=\"title  rts-text-anime-style-1\">Stay Updated with the Latest News! <span class=\"stroke_text\"><\/span><\/h2>\t\t\r\n\t\t\t<\/div>\t\r\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-76979ac elementor-widget__width-initial elementor-widget elementor-widget-metform\" data-id=\"76979ac\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"metform.default\">\n\t\t\t\t\t<div id=\"mf-response-props-id-2509\" data-previous-steps-style=\"\" data-editswitchopen=\"\" data-response_type=\"alert\" data-erroricon=\"fas fa-exclamation-triangle\" data-successicon=\"fas fa-check\" data-messageposition=\"top\" class=\"   mf-scroll-top-no\">\n\t\t<div class=\"formpicker_warper formpicker_warper_editable\" data-metform-formpicker-key=\"2509\" >\n\t\t\t\t\n\t\t\t<div class=\"mf-widget-container\">\n\t\t\t\t\r\n\t\t<div\r\n\t\t\tid=\"metform-wrap-76979ac-2509\"\r\n\t\t\tclass=\"mf-form-wrapper\"\r\n\t\t\tdata-form-id=\"2509\"\r\n\t\t\tdata-action=\"https:\/\/reactheme.com\/products\/wordpress\/invena\/coach\/wp-json\/metform\/v1\/entries\/insert\/2509\"\r\n\t\t\tdata-wp-nonce=\"71ceb9694f\"\r\n\t\t\tdata-form-nonce=\"351670e638\"\r\n\t\t\tdata-quiz-summery = \"false\"\r\n\t\t\tdata-save-progress = \"false\"\r\n\t\t\tdata-form-type=\"general-form\"\r\n\t\t\tdata-stop-vertical-effect=\"\"\r\n\t\t\t><\/div>\r\n\r\n\r\n\t\t<!----------------------------- \r\n\t\t\t* controls_data : find the the props passed indie of data attribute\r\n\t\t\t* props.SubmitResponseMarkup : contains the markup of error or success message\r\n\t\t\t* https:\/\/developer.mozilla.org\/en-US\/docs\/Web\/JavaScript\/Reference\/Template_literals\r\n\t\t--------------------------- -->\r\n\r\n\t\t\t\t<script type=\"text\/mf\" class=\"mf-template\">\r\n\t\t\tfunction controls_data (value){\r\n\t\t\t\tlet currentWrapper = \"mf-response-props-id-2509\";\r\n\t\t\t\tlet currentEl = document.getElementById(currentWrapper);\r\n\t\t\t\t\r\n\t\t\t\treturn currentEl ? currentEl.dataset[value] : false\r\n\t\t\t}\r\n\r\n\r\n\t\t\tlet is_edit_mode = '' ? true : false;\r\n\t\t\tlet message_position = controls_data('messageposition') || 'top';\r\n\r\n\t\t\t\r\n\t\t\tlet message_successIcon = controls_data('successicon') || '';\r\n\t\t\tlet message_errorIcon = controls_data('erroricon') || '';\r\n\t\t\tlet message_editSwitch = controls_data('editswitchopen') === 'yes' ? true : false;\r\n\t\t\tlet message_proClass = controls_data('editswitchopen') === 'yes' ? 'mf_pro_activated' : '';\r\n\t\t\t\r\n\t\t\tlet is_dummy_markup = is_edit_mode && message_editSwitch ? true : false;\r\n\r\n\t\t\t\r\n\t\t\treturn html`\r\n\t\t\t\t<form\r\n\t\t\t\t\tclassName=\"metform-form-content\"\r\n\t\t\t\t\tref=${parent.formContainerRef}\r\n\t\t\t\t\tonSubmit=${ validation.handleSubmit( parent.handleFormSubmit ) }\r\n\t\t\t\t\r\n\t\t\t\t\t>\r\n\t\t\t\r\n\t\t\t\r\n\t\t\t\t\t${is_dummy_markup ? message_position === 'top' ?  props.ResponseDummyMarkup(message_successIcon, message_proClass) : '' : ''}\r\n\t\t\t\t\t${is_dummy_markup ? ' ' :  message_position === 'top' ? props.SubmitResponseMarkup`${parent}${state}${message_successIcon}${message_errorIcon}${message_proClass}` : ''}\r\n\r\n\t\t\t\t\t<!--------------------------------------------------------\r\n\t\t\t\t\t*** IMPORTANT \/ DANGEROUS ***\r\n\t\t\t\t\t${html``} must be used as in immediate child of \"metform-form-main-wrapper\"\r\n\t\t\t\t\tclass otherwise multistep form will not run at all\r\n\t\t\t\t\t---------------------------------------------------------->\r\n\r\n\t\t\t\t\t<div className=\"metform-form-main-wrapper\" key=${'hide-form-after-submit'} ref=${parent.formRef}>\r\n\t\t\t\t\t${html`\r\n\t\t\t\t\t\t\t\t<div data-elementor-type=\"wp-post\" key=\"2\" data-elementor-id=\"2509\" className=\"elementor elementor-2509\">\n\t\t\t\t<div className=\"elementor-element elementor-element-7f3166e e-con-full e-flex e-con e-parent\" data-id=\"7f3166e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div className=\"elementor-element elementor-element-aed29a7 elementor-widget__width-inherit elementor-widget elementor-widget-mf-email\" data-id=\"aed29a7\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;mf_input_name&quot;:&quot;mf-email&quot;}\" data-widget_type=\"mf-email.default\">\n\t\t\t\t\t\r\n\t\t<div className=\"mf-input-wrapper\">\r\n\t\t\t\r\n\t\t\t<input \r\n\t\t\t\ttype=\"email\" \r\n\t\t\t\t \r\n\t\t\t\tdefaultValue=\"\" \r\n\t\t\t\tclassName=\"mf-input \" \r\n\t\t\t\tid=\"mf-input-email-aed29a7\" \r\n\t\t\t\tname=\"mf-email\" \r\n\t\t\t\tplaceholder=\"${ parent.decodeEntities(`Enter Email Address`) } \" \r\n\t\t\t\t \r\n\t\t\t\tonBlur=${parent.handleChange} onFocus=${parent.handleChange} aria-invalid=${validation.errors['mf-email'] ? 'true' : 'false' } \r\n\t\t\t\tref=${el=> parent.activateValidation({\"message\":\"This field is required.\",\"emailMessage\":\"Please enter a valid Email address\",\"minLength\":1,\"maxLength\":\"\",\"type\":\"none\",\"required\":true,\"expression\":\"null\"}, el)}\r\n\t\t\t\t\t\t\t\/>\r\n\r\n\t\t\t\t\t\t<${validation.ErrorMessage} \r\n\t\t\t\terrors=${validation.errors} \r\n\t\t\t\tname=\"mf-email\" \r\n\t\t\t\tas=${html`<span className=\"mf-error-message\"><\/span>`}\r\n\t\t\t\/>\r\n\t\t\t\r\n\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t<\/div>\n\t\t\t\t<div className=\"elementor-element elementor-element-bbfe91f elementor-absolute elementor-widget elementor-widget-mf-button\" data-id=\"bbfe91f\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"mf-button.default\">\n\t\t\t\t\t\t\t<div className=\"mf-btn-wraper \" data-mf-form-conditional-logic-requirement=\"\">\r\n\t\t\t\t\t\t\t<button type=\"submit\" className=\"metform-btn metform-submit-btn \" id=\"\">\r\n\t\t\t\t\t<span>${ parent.decodeEntities(`Subscribe Now`) } <\/span>\r\n\t\t\t\t<\/button>\r\n\t\t\t        <\/div>\r\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t`}\r\n\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t${is_dummy_markup ? message_position === 'bottom' ? props.ResponseDummyMarkup(message_successIcon, message_proClass) : '' : ''}\r\n\t\t\t\t\t${is_dummy_markup ? ' ' : message_position === 'bottom' ? props.SubmitResponseMarkup`${parent}${state}${message_successIcon}${message_errorIcon}${message_proClass}` : ''}\r\n\t\t\t\t\r\n\t\t\t\t<\/form>\r\n\t\t\t`\r\n\t\t<\/script>\r\n\r\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t<\/div>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Our Service Services We Provide With a team of experienced professionals and a passion for innovation, we combine cutting-edge strategies Business Solution we provide smart, scalable business solutions. Read More Business Solution Comprehensive marketing solutions designed. Read More Finance Solution Full-service agency marketing solutions that help brands. Read More Business Marketing Our business marketing services [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"footnotes":""},"class_list":["post-9734","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/reactheme.com\/products\/wordpress\/invena\/coach\/wp-json\/wp\/v2\/pages\/9734","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/reactheme.com\/products\/wordpress\/invena\/coach\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/reactheme.com\/products\/wordpress\/invena\/coach\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/reactheme.com\/products\/wordpress\/invena\/coach\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/reactheme.com\/products\/wordpress\/invena\/coach\/wp-json\/wp\/v2\/comments?post=9734"}],"version-history":[{"count":0,"href":"https:\/\/reactheme.com\/products\/wordpress\/invena\/coach\/wp-json\/wp\/v2\/pages\/9734\/revisions"}],"wp:attachment":[{"href":"https:\/\/reactheme.com\/products\/wordpress\/invena\/coach\/wp-json\/wp\/v2\/media?parent=9734"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}